{"id":17115,"date":"2023-07-05T02:50:52","date_gmt":"2023-07-05T02:50:52","guid":{"rendered":"https:\/\/www.justice4all.org\/que-hacemos\/sanidad-y-prestaciones-publicas\/inscripcion-en-el-seguro-de-enfermedad\/"},"modified":"2023-08-15T16:14:22","modified_gmt":"2023-08-15T16:14:22","slug":"inscripcion-en-el-seguro-de-enfermedad","status":"publish","type":"page","link":"https:\/\/www.justice4all.org\/es\/que-hacemos\/sanidad-y-prestaciones-publicas\/inscripcion-en-el-seguro-de-enfermedad\/","title":{"rendered":"Inscripci\u00f3n en el seguro de enfermedad"},"content":{"rendered":"\n\n\n  <style type=\"text\/css\">\n    #block_f98ed44bc32fb95bd56e9f55fae322a6 {\n                                        margin-left: calc(0 * 16px);\n                          margin-right: calc(0 * 16px);\n              \n                                        padding-left: calc(4 * 16px);\n                          padding-right: calc(4 * 16px);\n                  }\n\n    @media screen and (min-width: 768px) and (max-width: 991px) {\n      #block_f98ed44bc32fb95bd56e9f55fae322a6 {\n                                                  margin-left: calc(0 * 12px);  \n                                margin-right: calc(0 * 12px);  \n                    \n                                                  padding-left: calc(4 * 12px);\n                                padding-right: calc(4 * 12px);\n                        }\n    }\n\n    @media screen and (min-width: 480px) and (max-width: 767px) {\n      #block_f98ed44bc32fb95bd56e9f55fae322a6 {\n                                                  margin-left: calc(0 * 8px);  \n                                margin-right: calc(0 * 8px);  \n                    \n                                                  padding-left: calc(4 * 8px);\n                                padding-right: calc(4 * 8px);\n                        }\n    }\n\n    @media screen and (max-width: 479px) {\n      #block_f98ed44bc32fb95bd56e9f55fae322a6 {\n                                                  margin-left: calc(0 * 4px);  \n                                margin-right: calc(0 * 4px);  \n                    \n                                                  padding-left: calc(4 * 4px);\n                                padding-right: calc(4 * 4px);\n                        }\n    }\n\n  <\/style>\n\n\n<div id=\"block_f98ed44bc32fb95bd56e9f55fae322a6\" class=\"content-wrapper-block  style-normal bg-width-full \">\n\t<div class=\"container-fluid\">\n\t\t<div class=\"row justify-content-center\">\n\t\t\t<div class=\"col-lg-12\">\n\t\t\t\t\t\t\t\t\t<div class=\"row row-content justify-content-center\">\n\t\t\t\t\t\t\n\n\n\n\n<style type=\"text\/css\">\n\t.edit-post-visual-editor [data-block=\"fa4d1e17491935848d771f617734af83\"] {\n\t\twidth: calc((12 \/ 12) * 100%)!important;\n\t\tmin-width: calc((12 \/ 12) * 100%)!important;\n\t}\n<\/style>\n\n<div id=\"block_fa4d1e17491935848d771f617734af83\" class=\"col-lg-12 custom-column-block\">\n\t<div class=\"custom-column-wrapper  \">\n\t\t\n\n<h2 class=\"wp-block-heading is-style-underlined-with-icon has-gunpowder-color has-text-color\">CONOZCA SUS DERECHOS<\/h2>\n\n\n\n<h2 class=\"wp-block-heading has-gunpowder-color has-text-color\">INSCRIPCI\u00d3N EN EL SEGURO DE ENFERMEDAD<\/h2>\n\n\n\t<\/div>\n<\/div>\n\n\n\n\n\n<style type=\"text\/css\">\n\t.edit-post-visual-editor [data-block=\"fa4d1e17491935848d771f617734af83\"] {\n\t\twidth: calc((12 \/ 12) * 100%)!important;\n\t\tmin-width: calc((12 \/ 12) * 100%)!important;\n\t}\n<\/style>\n\n<div id=\"block_fa4d1e17491935848d771f617734af83\" class=\"col-lg-12 custom-column-block\">\n\t<div class=\"custom-column-wrapper  \">\n\t\t\n\n<p class=\"has-gunpowder-color has-text-color wp-block-paragraph\"><strong>\u00bfTiene preguntas sobre el seguro de enfermedad y la Ley de Asistencia Sanitaria Asequible? <\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tenemos navegadores de seguros de salud en el norte de Virginia (Falls Church y alrededores), Richmond (ciudad de Richmond, Petersburg y condados circundantes), Virginia Central (Charlottesville y condados circundantes) y el suroeste de Virginia (Washington, Grayson, Galax City, Russell, Smyth, Wythe y Bristol City). <\/p>\n\n\n\n<p class=\"has-purple-color has-text-color wp-block-paragraph\"><strong>Ll\u00e1menos. L\u00edneas directas de asistencia sobre seguros de enfermedad <\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Asistencia en ingl\u00e9s: 804-340-7747 <\/li>\n\n\n\n<li>Asistencia en espa\u00f1ol: 804-340-7738 <\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><em>Si vive fuera de nuestra zona de cobertura, visite <\/em><a href=\"http:\/\/www.enrollva.org\/\" target=\"_blank\" rel=\"noreferrer noopener\"><em>http:\/\/www.enrollva.org<\/em><\/a><em> para encontrar un navegador en su zona.<\/em><\/p>\n\n\n\t<\/div>\n<\/div>\n\n\n\n\n\n<style type=\"text\/css\">\n\t.edit-post-visual-editor [data-block=\"fa4d1e17491935848d771f617734af83\"] {\n\t\twidth: calc((12 \/ 12) * 100%)!important;\n\t\tmin-width: calc((12 \/ 12) * 100%)!important;\n\t}\n<\/style>\n\n<div id=\"block_fa4d1e17491935848d771f617734af83\" class=\"col-lg-12 custom-column-block\">\n\t<div class=\"custom-column-wrapper  \">\n\t\t\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity is-style-gradient-primary\"\/>\n\n\n\t<\/div>\n<\/div>\n\n\n\n\n\n<style type=\"text\/css\">\n\t.edit-post-visual-editor [data-block=\"fa4d1e17491935848d771f617734af83\"] {\n\t\twidth: calc((12 \/ 12) * 100%)!important;\n\t\tmin-width: calc((12 \/ 12) * 100%)!important;\n\t}\n<\/style>\n\n<div id=\"block_fa4d1e17491935848d771f617734af83\" class=\"col-lg-12 custom-column-block\">\n\t<div class=\"custom-column-wrapper  \">\n\t\t\n\n<h2 class=\"wp-block-heading is-style-underlined-with-icon has-gunpowder-color has-text-color\">La vuelta a la normalidad de la inscripci\u00f3n en Medicaid y la Ley de Asistencia Sanitaria Asequible <\/h2>\n\n\n\t<\/div>\n<\/div>\n\n\n\n\n\n<style type=\"text\/css\">\n\t.edit-post-visual-editor [data-block=\"fa4d1e17491935848d771f617734af83\"] {\n\t\twidth: calc((12 \/ 12) * 100%)!important;\n\t\tmin-width: calc((12 \/ 12) * 100%)!important;\n\t}\n<\/style>\n\n<div id=\"block_fa4d1e17491935848d771f617734af83\" class=\"col-lg-12 custom-column-block\">\n\t<div class=\"custom-column-wrapper  \">\n\t\t\n\n<p class=\"wp-block-paragraph\">A partir del 1 de abril de 2023, Virginia volvi\u00f3 a los procedimientos anteriores a la pandemia para determinar la elegibilidad para Medicaid cada a\u00f1o. Esto significa que todas las personas que se inscriben en Medicaid deben realizar una renovaci\u00f3n anual para volver a determinar si cumplen los requisitos. Los afiliados actuales a Medicaid recibir\u00e1n un aviso en el que se les informar\u00e1 de que el Estado ha podido renovar su cobertura con la informaci\u00f3n que ya tienen en sus archivos, como los ingresos procedentes de las prestaciones del SNAP, <em>o bien<\/em> recibir\u00e1n un paquete de renovaci\u00f3n que deber\u00e1n devolver en un plazo de 30 d\u00edas. Para m\u00e1s informaci\u00f3n sobre la vuelta a la inscripci\u00f3n en <a href=\"https:\/\/www.justice4all.org\/what-we-do\/healthcare-public-benefits\/health-insurance-enrollment\/end-of-medicaid-continuous-coverage\/\" target=\"_blank\" rel=\"noreferrer noopener\">Medicaid<\/a>, consulte El fin de la cobertura continua de Medicaid. <\/p>\n\n\n\n<p class=\"has-gunpowder-color has-text-color wp-block-paragraph\">Cualquier persona que ya no es elegible para Medicaid tiene dos oportunidades para inscribirse en un seguro de salud a trav\u00e9s de la Ley de Asistencia Asequible tan pronto como pierden su cobertura de Medicaid, estos son \u00abPer\u00edodos Especiales de Inscripci\u00f3n\u00bb. <\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Periodo de inscripci\u00f3n especial por p\u00e9rdida de cobertura <\/li>\n\n\n\n<li>Periodo de inscripci\u00f3n especial asociado a la vuelta a la inscripci\u00f3n normal <\/li>\n<\/ul>\n\n\n\n<p class=\"has-gunpowder-color has-text-color wp-block-paragraph\"><strong>Nuestros navegadores est\u00e1n ayudando a navegar por estos per\u00edodos especiales de inscripci\u00f3n y el proceso de inscripci\u00f3n a distancia y en persona. Llame ahora y concierte una cita: <\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Asistencia en ingl\u00e9s: 804-340-7747 <\/li>\n\n\n\n<li>Asistencia en espa\u00f1ol: 804-340-7738 <\/li>\n<\/ul>\n\n\n\t<\/div>\n<\/div>\n\n\n\n\n\n<style type=\"text\/css\">\n\t.edit-post-visual-editor [data-block=\"fa4d1e17491935848d771f617734af83\"] {\n\t\twidth: calc((12 \/ 12) * 100%)!important;\n\t\tmin-width: calc((12 \/ 12) * 100%)!important;\n\t}\n<\/style>\n\n<div id=\"block_fa4d1e17491935848d771f617734af83\" class=\"col-lg-12 custom-column-block\">\n\t<div class=\"custom-column-wrapper  \">\n\t\t\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity is-style-gradient-primary\"\/>\n\n\n\t<\/div>\n<\/div>\n\n\n\n\n\n<style type=\"text\/css\">\n\t.edit-post-visual-editor [data-block=\"fa4d1e17491935848d771f617734af83\"] {\n\t\twidth: calc((12 \/ 12) * 100%)!important;\n\t\tmin-width: calc((12 \/ 12) * 100%)!important;\n\t}\n<\/style>\n\n<div id=\"block_fa4d1e17491935848d771f617734af83\" class=\"col-lg-12 custom-column-block\">\n\t<div class=\"custom-column-wrapper  \">\n\t\t\n\n<p class=\"has-purple-color has-text-color has-medium-font-size wp-block-paragraph\"><strong>LA INSCRIPCI\u00d3N ABIERTA COMIENZA EL 1 DE NOVIEMBRE <\/strong><\/p>\n\n\n\n<p class=\"has-gunpowder-color has-text-color wp-block-paragraph\"><strong>Legal Aid est\u00e1 ayudando a navegar por el proceso de inscripci\u00f3n a distancia y en persona. Es hora de concertar una cita. Llama ahora: <\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Asistencia en ingl\u00e9s: 804-340-7747 <\/li>\n\n\n\n<li>Asistencia en espa\u00f1ol: 804-340-7738 <\/li>\n<\/ul>\n\n\n\t<\/div>\n<\/div>\n\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\n\t<style type=\"text\/css\">\n\t\t.edit-post-visual-editor [data-block=\"f98ed44bc32fb95bd56e9f55fae322a6\"] .block-editor-block-list__layout {\n\t\t\tjustify-content: center;\n\t\t}\n\n\t\t\t<\/style>\n<\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":4,"featured_media":0,"parent":13136,"menu_order":4,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"lajc-tax-roles":[],"lajc-tax-issues":[],"lajc-tax-locations":[],"class_list":["post-17115","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Inscripci\u00f3n en el seguro de enfermedad - Legal Aid Justice Center<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.justice4all.org\/es\/que-hacemos\/sanidad-y-prestaciones-publicas\/inscripcion-en-el-seguro-de-enfermedad\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Inscripci\u00f3n en el seguro de enfermedad - Legal Aid Justice Center\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.justice4all.org\/es\/que-hacemos\/sanidad-y-prestaciones-publicas\/inscripcion-en-el-seguro-de-enfermedad\/\" \/>\n<meta property=\"og:site_name\" content=\"Legal Aid Justice Center\" \/>\n<meta property=\"article:modified_time\" content=\"2023-08-15T16:14:22+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.justice4all.org\\\/es\\\/que-hacemos\\\/sanidad-y-prestaciones-publicas\\\/inscripcion-en-el-seguro-de-enfermedad\\\/\",\"url\":\"https:\\\/\\\/www.justice4all.org\\\/es\\\/que-hacemos\\\/sanidad-y-prestaciones-publicas\\\/inscripcion-en-el-seguro-de-enfermedad\\\/\",\"name\":\"Inscripci\u00f3n en el seguro de enfermedad - Legal Aid Justice Center\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.justice4all.org\\\/es\\\/#website\"},\"datePublished\":\"2023-07-05T02:50:52+00:00\",\"dateModified\":\"2023-08-15T16:14:22+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.justice4all.org\\\/es\\\/que-hacemos\\\/sanidad-y-prestaciones-publicas\\\/inscripcion-en-el-seguro-de-enfermedad\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.justice4all.org\\\/es\\\/que-hacemos\\\/sanidad-y-prestaciones-publicas\\\/inscripcion-en-el-seguro-de-enfermedad\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.justice4all.org\\\/es\\\/que-hacemos\\\/sanidad-y-prestaciones-publicas\\\/inscripcion-en-el-seguro-de-enfermedad\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.justice4all.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Qu\u00e9 hacemos\",\"item\":\"https:\\\/\\\/www.justice4all.org\\\/es\\\/que-hacemos\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Sanidad y prestaciones p\u00fablicas\",\"item\":\"https:\\\/\\\/www.justice4all.org\\\/es\\\/que-hacemos\\\/sanidad-y-prestaciones-publicas\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Inscripci\u00f3n en el seguro de enfermedad\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.justice4all.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.justice4all.org\\\/es\\\/\",\"name\":\"Legal Aid Justice Center\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.justice4all.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Inscripci\u00f3n en el seguro de enfermedad - Legal Aid Justice Center","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.justice4all.org\/es\/que-hacemos\/sanidad-y-prestaciones-publicas\/inscripcion-en-el-seguro-de-enfermedad\/","og_locale":"es_ES","og_type":"article","og_title":"Inscripci\u00f3n en el seguro de enfermedad - Legal Aid Justice Center","og_url":"https:\/\/www.justice4all.org\/es\/que-hacemos\/sanidad-y-prestaciones-publicas\/inscripcion-en-el-seguro-de-enfermedad\/","og_site_name":"Legal Aid Justice Center","article_modified_time":"2023-08-15T16:14:22+00:00","twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"2 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.justice4all.org\/es\/que-hacemos\/sanidad-y-prestaciones-publicas\/inscripcion-en-el-seguro-de-enfermedad\/","url":"https:\/\/www.justice4all.org\/es\/que-hacemos\/sanidad-y-prestaciones-publicas\/inscripcion-en-el-seguro-de-enfermedad\/","name":"Inscripci\u00f3n en el seguro de enfermedad - Legal Aid Justice Center","isPartOf":{"@id":"https:\/\/www.justice4all.org\/es\/#website"},"datePublished":"2023-07-05T02:50:52+00:00","dateModified":"2023-08-15T16:14:22+00:00","breadcrumb":{"@id":"https:\/\/www.justice4all.org\/es\/que-hacemos\/sanidad-y-prestaciones-publicas\/inscripcion-en-el-seguro-de-enfermedad\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.justice4all.org\/es\/que-hacemos\/sanidad-y-prestaciones-publicas\/inscripcion-en-el-seguro-de-enfermedad\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.justice4all.org\/es\/que-hacemos\/sanidad-y-prestaciones-publicas\/inscripcion-en-el-seguro-de-enfermedad\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.justice4all.org\/es\/"},{"@type":"ListItem","position":2,"name":"Qu\u00e9 hacemos","item":"https:\/\/www.justice4all.org\/es\/que-hacemos\/"},{"@type":"ListItem","position":3,"name":"Sanidad y prestaciones p\u00fablicas","item":"https:\/\/www.justice4all.org\/es\/que-hacemos\/sanidad-y-prestaciones-publicas\/"},{"@type":"ListItem","position":4,"name":"Inscripci\u00f3n en el seguro de enfermedad"}]},{"@type":"WebSite","@id":"https:\/\/www.justice4all.org\/es\/#website","url":"https:\/\/www.justice4all.org\/es\/","name":"Legal Aid Justice Center","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.justice4all.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"}]}},"_links":{"self":[{"href":"https:\/\/www.justice4all.org\/es\/wp-json\/wp\/v2\/pages\/17115","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.justice4all.org\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.justice4all.org\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.justice4all.org\/es\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.justice4all.org\/es\/wp-json\/wp\/v2\/comments?post=17115"}],"version-history":[{"count":0,"href":"https:\/\/www.justice4all.org\/es\/wp-json\/wp\/v2\/pages\/17115\/revisions"}],"up":[{"embeddable":true,"href":"https:\/\/www.justice4all.org\/es\/wp-json\/wp\/v2\/pages\/13136"}],"wp:attachment":[{"href":"https:\/\/www.justice4all.org\/es\/wp-json\/wp\/v2\/media?parent=17115"}],"wp:term":[{"taxonomy":"lajc-tax-roles","embeddable":true,"href":"https:\/\/www.justice4all.org\/es\/wp-json\/wp\/v2\/lajc-tax-roles?post=17115"},{"taxonomy":"lajc-tax-issues","embeddable":true,"href":"https:\/\/www.justice4all.org\/es\/wp-json\/wp\/v2\/lajc-tax-issues?post=17115"},{"taxonomy":"lajc-tax-locations","embeddable":true,"href":"https:\/\/www.justice4all.org\/es\/wp-json\/wp\/v2\/lajc-tax-locations?post=17115"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}