{"id":10499,"date":"2022-07-21T15:00:30","date_gmt":"2022-07-21T15:00:30","guid":{"rendered":"https:\/\/lajc2023stg.wpengine.com\/que-hacemos\/juventud-familia-y-escuelas\/matricula-escolar-derechos-y-deberes\/"},"modified":"2023-07-25T21:51:26","modified_gmt":"2023-07-25T21:51:26","slug":"matricula-escolar-derechos-y-deberes","status":"publish","type":"page","link":"https:\/\/www.justice4all.org\/es\/que-hacemos\/juventud-familia-y-escuelas\/matricula-escolar-derechos-y-deberes\/","title":{"rendered":"Matr\u00edcula escolar: Derechos y deberes"},"content":{"rendered":"\n\n\n\n<style type=\"text\/css\">\n\t.edit-post-visual-editor [data-block=\"a4a8bdacf66625b14905963bc08db5bc\"] {\n\t\twidth: calc((12 \/ 12) * 100%)!important;\n\t\tmin-width: calc((12 \/ 12) * 100%)!important;\n\t}\n<\/style>\n\n<div id=\"block_a4a8bdacf66625b14905963bc08db5bc\" class=\"col-lg-12 custom-column-block\">\n\t<div class=\"custom-column-wrapper  \">\n\t\t\n\n\n\n  <style type=\"text\/css\">\n    #block_c1d412661881873b4a812ab3fcff353e > div{\n                                        margin-left: calc(8 * 16px);\n                          margin-right: calc(8 * 16px);\n              \n                                        padding-left: calc(8 * 16px);\n                          padding-right: calc(8 * 16px);\n                  }\n\n    @media screen and (min-width: 768px) and (max-width: 991px) {\n      #block_c1d412661881873b4a812ab3fcff353e > div{\n                                                  margin-left: calc(8 * 12px);  \n                                margin-right: calc(8 * 12px);  \n                    \n                                                  padding-left: calc(8 * 12px);\n                                padding-right: calc(8 * 12px);\n                        }\n    }\n\n    @media screen and (min-width: 480px) and (max-width: 767px) {\n      #block_c1d412661881873b4a812ab3fcff353e > div{\n                                                  margin-left: calc(8 * 8px);  \n                                margin-right: calc(8 * 8px);  \n                    \n                                                  padding-left: calc(8 * 8px);\n                                padding-right: calc(8 * 8px);\n                        }\n    }\n\n    @media screen and (max-width: 479px) {\n      #block_c1d412661881873b4a812ab3fcff353e > div{\n                                                  margin-left: calc(8 * 4px);  \n                                margin-right: calc(8 * 4px);  \n                    \n                                                  padding-left: calc(8 * 4px);\n                                padding-right: calc(8 * 4px);\n                        }\n    }\n\n  <\/style>\n\n<style type=\"text\/css\">\n\t.edit-post-visual-editor [data-block=\"c1d412661881873b4a812ab3fcff353e\"] {\n\t\twidth: calc((12 \/ 12) * 100%)!important;\n\t\tmin-width: calc((12 \/ 12) * 100%)!important;\n\t}\n<\/style>\n\n<div id=\"block_c1d412661881873b4a812ab3fcff353e\" class=\"col-lg-12 custom-column-block\">\n\t<div class=\"custom-column-wrapper  \">\n\t\t\n\n<h2 class=\"wp-block-heading is-style-underlined-with-icon\">CONOZCA SUS DERECHOS:<\/h2>\n\n\n\n<h2 class=\"wp-block-heading has-gunpowder-color has-text-color\">Matr\u00edcula escolar: Derechos y deberes<\/h2>\n\n\n\t<\/div>\n<\/div>\n\n\n\n\n  <style type=\"text\/css\">\n    #block_c1d412661881873b4a812ab3fcff353e > div{\n                                        margin-left: calc(8 * 16px);\n                          margin-right: calc(8 * 16px);\n              \n                                        padding-left: calc(8 * 16px);\n                          padding-right: calc(8 * 16px);\n                  }\n\n    @media screen and (min-width: 768px) and (max-width: 991px) {\n      #block_c1d412661881873b4a812ab3fcff353e > div{\n                                                  margin-left: calc(8 * 12px);  \n                                margin-right: calc(8 * 12px);  \n                    \n                                                  padding-left: calc(8 * 12px);\n                                padding-right: calc(8 * 12px);\n                        }\n    }\n\n    @media screen and (min-width: 480px) and (max-width: 767px) {\n      #block_c1d412661881873b4a812ab3fcff353e > div{\n                                                  margin-left: calc(8 * 8px);  \n                                margin-right: calc(8 * 8px);  \n                    \n                                                  padding-left: calc(8 * 8px);\n                                padding-right: calc(8 * 8px);\n                        }\n    }\n\n    @media screen and (max-width: 479px) {\n      #block_c1d412661881873b4a812ab3fcff353e > div{\n                                                  margin-left: calc(8 * 4px);  \n                                margin-right: calc(8 * 4px);  \n                    \n                                                  padding-left: calc(8 * 4px);\n                                padding-right: calc(8 * 4px);\n                        }\n    }\n\n  <\/style>\n\n<style type=\"text\/css\">\n\t.edit-post-visual-editor [data-block=\"c1d412661881873b4a812ab3fcff353e\"] {\n\t\twidth: calc((12 \/ 12) * 100%)!important;\n\t\tmin-width: calc((12 \/ 12) * 100%)!important;\n\t}\n<\/style>\n\n<div id=\"block_c1d412661881873b4a812ab3fcff353e\" class=\"col-lg-12 custom-column-block\">\n\t<div class=\"custom-column-wrapper  \">\n\t\t\n\n<p class=\"wp-block-paragraph\"><strong>Qui\u00e9n:<\/strong> Todos los ni\u00f1os que cumplan cinco a\u00f1os antes del 30 de septiembre y hasta los 18 a\u00f1os est\u00e1n obligados por la ley de Virginia a matricularse en una escuela p\u00fablica, privada o en una escuela en casa aprobada por el estado<sup>.1 <\/sup>En general, los alumnos pueden matricularse en la escuela hasta los 20 a\u00f1os o hasta que se <sup>grad\u00faen2<\/sup>. Los alumnos con Programas Educativos Individualizados (IEP) pueden asistir a la escuela hasta los 21 a\u00f1os<sup>.3<\/sup> Los alumnos de 12 a\u00f1os o m\u00e1s que se matriculen por primera vez en una escuela p\u00fablica de Virginia y sean identificados como Estudiantes de Lengua Inglesa pueden permanecer en la escuela hasta los 22 a\u00f1os<sup>.4<\/sup><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>D\u00f3nde:  <\/strong>A menos que un ni\u00f1o tenga una variante (lo que significa que la divisi\u00f3n escolar aprob\u00f3 una escuela diferente a la escuela de la zona del ni\u00f1o), no tenga hogar, est\u00e9 en cuidado familiar (viviendo con un pariente que no es un padre) o en un entorno de cuidado de crianza, el ni\u00f1o debe asistir a la divisi\u00f3n escolar donde reside el padre o tutor del ni\u00f1o. La residencia debe ser \u00abde buena fe\u00bb, es decir, no debe tener como \u00fanico fin asistir a la<sup>escuela5<\/sup>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Las familias y las situaciones vitales se complican - si tiene alguna pregunta sobre d\u00f3nde deber\u00eda escolarizar a su hijo, p\u00f3ngase en contacto con nosotros <a href=\"https:\/\/www.justice4all.org\/es\/obtener-ayuda\/\">\n  <strong>aqu\u00ed<\/strong>\n<\/a>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>C\u00f3mo:  <\/strong>Llame a su escuela local o consulte el sitio web de su divisi\u00f3n escolar para obtener informaci\u00f3n espec\u00edfica sobre c\u00f3mo inscribirse, pero la ley de Virginia exige ciertos documentos antes de la inscripci\u00f3n: Una copia certificada del certificado de nacimiento del ni\u00f1o (o una declaraci\u00f3n jurada que establezca la edad del ni\u00f1o y explique la raz\u00f3n por la que no se puede obtener una copia certificada del certificado de nacimiento del ni\u00f1o - si se utiliza, se notificar\u00e1 a la polic\u00eda); prueba de residencia, como facturas de servicios p\u00fablicos y un contrato de arrendamiento (a menos que existan circunstancias especiales); y un formulario de examen f\u00edsico escolar que incluya el registro de vacunaci\u00f3n.<sup>6<\/sup><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Cu\u00e1ndo<\/strong>: Se espera que los padres inscriban a los alumnos en la escuela lo antes posible, de acuerdo con el calendario local de inicio de curso.  <\/p>\n\n\n\t<\/div>\n<\/div>\n\n\n\n\n\n\n<div id=\"block_1f9a6efba0d484f2894a92586384d13c\" class=\"content-wrapper-block has-background-color has-carb\u00f3n-background-color style-en \u00e1ngulo bg-width-full \">\n\t<div class=\"container-fluid\">\n\t\t<div class=\"row justify-content-center\">\n\t\t\t<div class=\"col-lg-12\">\n\t\t\t\t\t\t\t\t\t<div class=\"row row-content justify-content-center\">\n\t\t\t\t\t\t\n\n\n\n\n<style type=\"text\/css\">\n\t.edit-post-visual-editor [data-block=\"a4a8bdacf66625b14905963bc08db5bc\"] {\n\t\twidth: calc((12 \/ 12) * 100%)!important;\n\t\tmin-width: calc((12 \/ 12) * 100%)!important;\n\t}\n<\/style>\n\n<div id=\"block_a4a8bdacf66625b14905963bc08db5bc\" class=\"col-lg-12 custom-column-block\">\n\t<div class=\"custom-column-wrapper  \">\n\t\t\n\n\n\n  <style type=\"text\/css\">\n    #block_697edae076b09f248d325032dd840759 > div{\n      \n                                        padding-left: calc(8 * 16px);\n                          padding-right: calc(8 * 16px);\n                  }\n\n    @media screen and (min-width: 768px) and (max-width: 991px) {\n      #block_697edae076b09f248d325032dd840759 > div{\n          \n                                                  padding-left: calc(8 * 12px);\n                                padding-right: calc(8 * 12px);\n                        }\n    }\n\n    @media screen and (min-width: 480px) and (max-width: 767px) {\n      #block_697edae076b09f248d325032dd840759 > div{\n          \n                                                  padding-left: calc(8 * 8px);\n                                padding-right: calc(8 * 8px);\n                        }\n    }\n\n    @media screen and (max-width: 479px) {\n      #block_697edae076b09f248d325032dd840759 > div{\n          \n                                                  padding-left: calc(8 * 4px);\n                                padding-right: calc(8 * 4px);\n                        }\n    }\n\n  <\/style>\n\n<style type=\"text\/css\">\n\t.edit-post-visual-editor [data-block=\"697edae076b09f248d325032dd840759\"] {\n\t\twidth: calc((12 \/ 12) * 100%)!important;\n\t\tmin-width: calc((12 \/ 12) * 100%)!important;\n\t}\n<\/style>\n\n<div id=\"block_697edae076b09f248d325032dd840759\" class=\"col-lg-12 custom-column-block\">\n\t<div class=\"custom-column-wrapper  \">\n\t\t\n\n<h2 class=\"wp-block-heading has-white-color has-text-color\">Cuestiones jur\u00eddicas comunes y preguntas frecuentes<\/h2>\n\n\n\t<\/div>\n<\/div>\n\n\n\n\n\n<style type=\"text\/css\">\n\t.edit-post-visual-editor [data-block=\"a4a8bdacf66625b14905963bc08db5bc\"] {\n\t\twidth: calc((12 \/ 12) * 100%)!important;\n\t\tmin-width: calc((12 \/ 12) * 100%)!important;\n\t}\n<\/style>\n\n<div id=\"block_a4a8bdacf66625b14905963bc08db5bc\" class=\"col-lg-12 custom-column-block\">\n\t<div class=\"custom-column-wrapper  \">\n\t\t\n\n\n\n  <style type=\"text\/css\">\n    #block_4d255f41e115f3dae26ba933598dcd43 {\n      \n                                        padding-left: calc(8 * 16px);\n                          padding-right: calc(8 * 16px);\n                  }\n\n    @media screen and (min-width: 768px) and (max-width: 991px) {\n      #block_4d255f41e115f3dae26ba933598dcd43 {\n          \n                                                  padding-left: calc(8 * 12px);\n                                padding-right: calc(8 * 12px);\n                        }\n    }\n\n    @media screen and (min-width: 480px) and (max-width: 767px) {\n      #block_4d255f41e115f3dae26ba933598dcd43 {\n          \n                                                  padding-left: calc(8 * 8px);\n                                padding-right: calc(8 * 8px);\n                        }\n    }\n\n    @media screen and (max-width: 479px) {\n      #block_4d255f41e115f3dae26ba933598dcd43 {\n          \n                                                  padding-left: calc(8 * 4px);\n                                padding-right: calc(8 * 4px);\n                        }\n    }\n\n  <\/style>\n\n\n<div id=\"block_4d255f41e115f3dae26ba933598dcd43\" class=\"accordion-section-block\">\n  <div class=\"container-fluid\">\n              <div class=\"accordion-section-heading-wrapper has-charcoal-background-color has-background-color\">\n          <div class=\"row row-heading\">\n            <div class=\"col-sm-12\">\n              <h2>Cambios de custodia o mudanzas<\/h2>\n              <p><\/p>\n              <span class=\"toggler\"><\/span>\n            <\/div>\n          <\/div>\n        <\/div>\n      \n      <div class=\"accordion-section-cols-wrapper has-whisper-background-color has-background-color\">\n        <div class=\"row row-cols\">\n          \n\n\n\n\n<style type=\"text\/css\">\n\t.edit-post-visual-editor [data-block=\"a4a8bdacf66625b14905963bc08db5bc\"] {\n\t\twidth: calc((12 \/ 12) * 100%)!important;\n\t\tmin-width: calc((12 \/ 12) * 100%)!important;\n\t}\n<\/style>\n\n<div id=\"block_a4a8bdacf66625b14905963bc08db5bc\" class=\"col-lg-12 custom-column-block\">\n\t<div class=\"custom-column-wrapper  \">\n\t\t\n\n<p class=\"has-charcoal-color has-text-color wp-block-paragraph\">Muchos ni\u00f1os de Virginia se mudan a lo largo del curso escolar y durante el verano debido a cambios en su situaci\u00f3n familiar y\/o vital. Las leyes federales y estatales pretenden mantener a los ni\u00f1os en la escuela a pesar de estas interrupciones.  <\/p>\n\n\n\n<p class=\"has-charcoal-color has-text-color wp-block-paragraph\">Si el ni\u00f1o est\u00e1 en acogida, vive con un familiar no progenitor o se aloja temporalmente en alg\u00fan lugar, existen protecciones legales especiales para que pueda asistir a la escuela. Tambi\u00e9n existen protecciones legales para que el ni\u00f1o pueda matricularse sin la documentaci\u00f3n adecuada. Si tienes alguna pregunta sobre estas protecciones, ponte en contacto con el Programa de Justicia Juvenil.  <\/p>\n\n\n\n<p class=\"has-charcoal-color has-text-color wp-block-paragraph\">Cuando el cuidador del menor no es su padre, madre o tutor, el menor sigue teniendo el derecho (y la obligaci\u00f3n) de matricularse en la escuela del lugar donde reside, siempre que no viva all\u00ed \u00fanicamente con fines escolares (\u00abresidencia de buena fe\u00bb). Una escuela no debe exigir una orden de tutela ni requerir que el adulto solicite la custodia para establecer la residencia del menor si la residencia de buena fe puede establecerse de otras maneras<sup>.7<\/sup> <\/p>\n\n\n\n<p class=\"has-charcoal-color has-text-color wp-block-paragraph\">Si los padres del ni\u00f1o viven fuera del estado y el ni\u00f1o ha residido con el adulto durante 60 d\u00edas o m\u00e1s, el adulto debe matricular al ni\u00f1o en una escuela de Virginia.  <em>y<\/em>  debe pagar los gastos de escolarizaci\u00f3n del ni\u00f1o o debe encontrar la manera de que otros paguen los gastos de escolarizaci\u00f3n del ni\u00f1o.<sup>8<\/sup><\/p>\n\n\n\t<\/div>\n<\/div>\n\n        <\/div>\n      <\/div>\n  <\/div>\n<\/div>\n\n\n\n\n  <style type=\"text\/css\">\n    #block_59db0e9b40754db9d9f821994ec4ef04 {\n      \n                                        padding-left: calc(8 * 16px);\n                          padding-right: calc(8 * 16px);\n                  }\n\n    @media screen and (min-width: 768px) and (max-width: 991px) {\n      #block_59db0e9b40754db9d9f821994ec4ef04 {\n          \n                                                  padding-left: calc(8 * 12px);\n                                padding-right: calc(8 * 12px);\n                        }\n    }\n\n    @media screen and (min-width: 480px) and (max-width: 767px) {\n      #block_59db0e9b40754db9d9f821994ec4ef04 {\n          \n                                                  padding-left: calc(8 * 8px);\n                                padding-right: calc(8 * 8px);\n                        }\n    }\n\n    @media screen and (max-width: 479px) {\n      #block_59db0e9b40754db9d9f821994ec4ef04 {\n          \n                                                  padding-left: calc(8 * 4px);\n                                padding-right: calc(8 * 4px);\n                        }\n    }\n\n  <\/style>\n\n\n<div id=\"block_59db0e9b40754db9d9f821994ec4ef04\" class=\"accordion-section-block\">\n  <div class=\"container-fluid\">\n              <div class=\"accordion-section-heading-wrapper has-charcoal-background-color has-background-color\">\n          <div class=\"row row-heading\">\n            <div class=\"col-sm-12\">\n              <h2>Presencia legal<\/h2>\n              <p><\/p>\n              <span class=\"toggler\"><\/span>\n            <\/div>\n          <\/div>\n        <\/div>\n      \n      <div class=\"accordion-section-cols-wrapper has-whisper-background-color has-background-color\">\n        <div class=\"row row-cols\">\n          \n\n\n\n\n<style type=\"text\/css\">\n\t.edit-post-visual-editor [data-block=\"a4a8bdacf66625b14905963bc08db5bc\"] {\n\t\twidth: calc((12 \/ 12) * 100%)!important;\n\t\tmin-width: calc((12 \/ 12) * 100%)!important;\n\t}\n<\/style>\n\n<div id=\"block_a4a8bdacf66625b14905963bc08db5bc\" class=\"col-lg-12 custom-column-block\">\n\t<div class=\"custom-column-wrapper  \">\n\t\t\n\n<p class=\"has-charcoal-color has-text-color wp-block-paragraph\">Los ni\u00f1os residentes en Virginia tienen derecho a asistir a la escuela p\u00fablica independientemente de su situaci\u00f3n migratoria o la de sus padres<sup>.9<\/sup> Los sistemas escolares no pueden exigir ni siquiera solicitar informaci\u00f3n sobre la situaci\u00f3n migratoria de un ni\u00f1o o de sus padres a efectos de matriculaci\u00f3n.<\/p>\n\n\n\t<\/div>\n<\/div>\n\n        <\/div>\n      <\/div>\n  <\/div>\n<\/div>\n\n\n\n\n  <style type=\"text\/css\">\n    #block_2c80530b6c7d9dc5f3f4bdbb72a3fc85 {\n      \n                                        padding-left: calc(8 * 16px);\n                          padding-right: calc(8 * 16px);\n                  }\n\n    @media screen and (min-width: 768px) and (max-width: 991px) {\n      #block_2c80530b6c7d9dc5f3f4bdbb72a3fc85 {\n          \n                                                  padding-left: calc(8 * 12px);\n                                padding-right: calc(8 * 12px);\n                        }\n    }\n\n    @media screen and (min-width: 480px) and (max-width: 767px) {\n      #block_2c80530b6c7d9dc5f3f4bdbb72a3fc85 {\n          \n                                                  padding-left: calc(8 * 8px);\n                                padding-right: calc(8 * 8px);\n                        }\n    }\n\n    @media screen and (max-width: 479px) {\n      #block_2c80530b6c7d9dc5f3f4bdbb72a3fc85 {\n          \n                                                  padding-left: calc(8 * 4px);\n                                padding-right: calc(8 * 4px);\n                        }\n    }\n\n  <\/style>\n\n\n<div id=\"block_2c80530b6c7d9dc5f3f4bdbb72a3fc85\" class=\"accordion-section-block\">\n  <div class=\"container-fluid\">\n              <div class=\"accordion-section-heading-wrapper has-charcoal-background-color has-background-color\">\n          <div class=\"row row-heading\">\n            <div class=\"col-sm-12\">\n              <h2>Ni\u00f1os asignados a PEI<\/h2>\n              <p><\/p>\n              <span class=\"toggler\"><\/span>\n            <\/div>\n          <\/div>\n        <\/div>\n      \n      <div class=\"accordion-section-cols-wrapper has-whisper-background-color has-background-color\">\n        <div class=\"row row-cols\">\n          \n\n\n\n\n<style type=\"text\/css\">\n\t.edit-post-visual-editor [data-block=\"a4a8bdacf66625b14905963bc08db5bc\"] {\n\t\twidth: calc((12 \/ 12) * 100%)!important;\n\t\tmin-width: calc((12 \/ 12) * 100%)!important;\n\t}\n<\/style>\n\n<div id=\"block_a4a8bdacf66625b14905963bc08db5bc\" class=\"col-lg-12 custom-column-block\">\n\t<div class=\"custom-column-wrapper  \">\n\t\t\n\n<p class=\"has-charcoal-color has-text-color wp-block-paragraph\">Los ni\u00f1os que tienen un Programa Educativo Individualizado (IEP) pueden asistir a un colegio privado o a un colegio fuera de su divisi\u00f3n. El equipo del PEI decide si el ni\u00f1o necesita este tipo de colocaci\u00f3n. La divisi\u00f3n escolar local sigue siendo responsable de garantizar que el menor reciba los servicios educativos adecuados, aunque est\u00e9 matriculado en un centro privado<sup>.10<\/sup><\/p>\n\n\n\n<p class=\"has-charcoal-color has-text-color wp-block-paragraph\">Si un ni\u00f1o tiene un IEP y est\u00e1 en acogida, existen protecciones legales adicionales para su escolarizaci\u00f3n, matriculaci\u00f3n y transporte. Si tienes alguna pregunta sobre estas protecciones, ponte en contacto con el Programa de Justicia Juvenil.  <\/p>\n\n\n\t<\/div>\n<\/div>\n\n        <\/div>\n      <\/div>\n  <\/div>\n<\/div>\n\n\t<\/div>\n<\/div>\n\n\t<\/div>\n<\/div>\n\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\n\t<style type=\"text\/css\">\n\t\t.edit-post-visual-editor [data-block=\"1f9a6efba0d484f2894a92586384d13c\"] .block-editor-block-list__layout {\n\t\t\tjustify-content: center;\n\t\t}\n\n\t\t\t<\/style>\n<\/div>\n\n\n\n\n\n\n<style type=\"text\/css\">\n\t.edit-post-visual-editor [data-block=\"a4a8bdacf66625b14905963bc08db5bc\"] {\n\t\twidth: calc((12 \/ 12) * 100%)!important;\n\t\tmin-width: calc((12 \/ 12) * 100%)!important;\n\t}\n<\/style>\n\n<div id=\"block_a4a8bdacf66625b14905963bc08db5bc\" class=\"col-lg-12 custom-column-block\">\n\t<div class=\"custom-column-wrapper  \">\n\t\t\n\n\n\n  <style type=\"text\/css\">\n    #block_c1d412661881873b4a812ab3fcff353e > div{\n                                        margin-left: calc(8 * 16px);\n                          margin-right: calc(8 * 16px);\n              \n                                        padding-left: calc(8 * 16px);\n                          padding-right: calc(8 * 16px);\n                  }\n\n    @media screen and (min-width: 768px) and (max-width: 991px) {\n      #block_c1d412661881873b4a812ab3fcff353e > div{\n                                                  margin-left: calc(8 * 12px);  \n                                margin-right: calc(8 * 12px);  \n                    \n                                                  padding-left: calc(8 * 12px);\n                                padding-right: calc(8 * 12px);\n                        }\n    }\n\n    @media screen and (min-width: 480px) and (max-width: 767px) {\n      #block_c1d412661881873b4a812ab3fcff353e > div{\n                                                  margin-left: calc(8 * 8px);  \n                                margin-right: calc(8 * 8px);  \n                    \n                                                  padding-left: calc(8 * 8px);\n                                padding-right: calc(8 * 8px);\n                        }\n    }\n\n    @media screen and (max-width: 479px) {\n      #block_c1d412661881873b4a812ab3fcff353e > div{\n                                                  margin-left: calc(8 * 4px);  \n                                margin-right: calc(8 * 4px);  \n                    \n                                                  padding-left: calc(8 * 4px);\n                                padding-right: calc(8 * 4px);\n                        }\n    }\n\n  <\/style>\n\n<style type=\"text\/css\">\n\t.edit-post-visual-editor [data-block=\"c1d412661881873b4a812ab3fcff353e\"] {\n\t\twidth: calc((12 \/ 12) * 100%)!important;\n\t\tmin-width: calc((12 \/ 12) * 100%)!important;\n\t}\n<\/style>\n\n<div id=\"block_c1d412661881873b4a812ab3fcff353e\" class=\"col-lg-12 custom-column-block\">\n\t<div class=\"custom-column-wrapper  \">\n\t\t\n\n<div class=\"wp-block-buttons is-content-justification-center is-layout-flex wp-container-core-buttons-is-layout-fe48e5de wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button is-style-primary\"><a class=\"wp-block-button__link wp-element-button\" href=\"https:\/\/www.justice4all.org\/wp-content\/uploads\/2023\/05\/DESIGN_School-Enrollment-2.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">DESCARGAR COMO PDF<\/a><\/div>\n\n\n\n<div class=\"wp-block-button is-style-secondary\"><a class=\"wp-block-button__link wp-element-button\" href=\"https:\/\/www.justice4all.org\/wp-content\/uploads\/2023\/05\/DESIGN_School-Enrollment_SPA.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">DOWNLOAD IN ENGLISH<\/a><\/div>\n<\/div>\n\n\n\t<\/div>\n<\/div>\n\n\t<\/div>\n<\/div>\n\n\n\n\n\n\n<div id=\"block_1f9a6efba0d484f2894a92586384d13c\" class=\"content-wrapper-block has-background-color has-carb\u00f3n-background-color style-en \u00e1ngulo bg-width-full \">\n\t<div class=\"container-fluid\">\n\t\t<div class=\"row justify-content-center\">\n\t\t\t<div class=\"col-lg-12\">\n\t\t\t\t\t\t\t\t\t<div class=\"row row-content justify-content-center\">\n\t\t\t\t\t\t\n\n\n\n\n<style type=\"text\/css\">\n\t.edit-post-visual-editor [data-block=\"a4a8bdacf66625b14905963bc08db5bc\"] {\n\t\twidth: calc((12 \/ 12) * 100%)!important;\n\t\tmin-width: calc((12 \/ 12) * 100%)!important;\n\t}\n<\/style>\n\n<div id=\"block_a4a8bdacf66625b14905963bc08db5bc\" class=\"col-lg-12 custom-column-block\">\n\t<div class=\"custom-column-wrapper  \">\n\t\t\n\n\n\n\n<style type=\"text\/css\">\n\t.edit-post-visual-editor [data-block=\"a4a8bdacf66625b14905963bc08db5bc\"] {\n\t\twidth: calc((12 \/ 12) * 100%)!important;\n\t\tmin-width: calc((12 \/ 12) * 100%)!important;\n\t}\n<\/style>\n\n<div id=\"block_a4a8bdacf66625b14905963bc08db5bc\" class=\"col-lg-12 custom-column-block\">\n\t<div class=\"custom-column-wrapper  \">\n\t\t\n\n\n\n  <style type=\"text\/css\">\n    #block_6e53dca3233467315ce049eb9565539f {\n      \n                                        padding-left: calc(8 * 16px);\n                          padding-right: calc(8 * 16px);\n                  }\n\n    @media screen and (min-width: 768px) and (max-width: 991px) {\n      #block_6e53dca3233467315ce049eb9565539f {\n          \n                                                  padding-left: calc(8 * 12px);\n                                padding-right: calc(8 * 12px);\n                        }\n    }\n\n    @media screen and (min-width: 480px) and (max-width: 767px) {\n      #block_6e53dca3233467315ce049eb9565539f {\n          \n                                                  padding-left: calc(8 * 8px);\n                                padding-right: calc(8 * 8px);\n                        }\n    }\n\n    @media screen and (max-width: 479px) {\n      #block_6e53dca3233467315ce049eb9565539f {\n          \n                                                  padding-left: calc(8 * 4px);\n                                padding-right: calc(8 * 4px);\n                        }\n    }\n\n  <\/style>\n\n\n<div id=\"block_6e53dca3233467315ce049eb9565539f\" class=\"accordion-section-block\">\n  <div class=\"container-fluid\">\n              <div class=\"accordion-section-heading-wrapper has-charcoal-background-color has-background-color\">\n          <div class=\"row row-heading\">\n            <div class=\"col-sm-12\">\n              <h2>Opciones de colocaci\u00f3n cuando un ni\u00f1o no quiere ir a la escuela<\/h2>\n              <p><\/p>\n              <span class=\"toggler\"><\/span>\n            <\/div>\n          <\/div>\n        <\/div>\n      \n      <div class=\"accordion-section-cols-wrapper has-whisper-background-color has-background-color\">\n        <div class=\"row row-cols\">\n          \n\n\n\n\n<style type=\"text\/css\">\n\t.edit-post-visual-editor [data-block=\"a4a8bdacf66625b14905963bc08db5bc\"] {\n\t\twidth: calc((12 \/ 12) * 100%)!important;\n\t\tmin-width: calc((12 \/ 12) * 100%)!important;\n\t}\n<\/style>\n\n<div id=\"block_a4a8bdacf66625b14905963bc08db5bc\" class=\"col-lg-12 custom-column-block\">\n\t<div class=\"custom-column-wrapper  \">\n\t\t\n\n<ul class=\"has-charcoal-color has-text-color wp-block-list\">\n<li>Virginia tiene una ley de asistencia obligatoria, lo que significa que todos los j\u00f3venes que tengan al menos cinco a\u00f1os y menos de 18 el 30 de septiembre de cualquier a\u00f1o o antes deben estar escolarizados<sup>.11<\/sup><\/li>\n\n\n\n<li>Las divisiones escolares pueden tener programas educativos, llamados programas de asistencia alternativa, que permiten a un alumno asistir a otra escuela p\u00fablica, ya sea en la divisi\u00f3n en la que reside el alumno o en otra divisi\u00f3n elegida por el padre o cuidador.  <\/li>\n\n\n\n<li>Compruebe las pol\u00edticas del Consejo de su divisi\u00f3n escolar local para ver si su divisi\u00f3n participa en un programa de asistencia alternativa.  <\/li>\n\n\n\n<li>Consulte el sitio web de su divisi\u00f3n escolar local o p\u00f3ngase en contacto con la divisi\u00f3n para informarse sobre otros programas, como programas de formaci\u00f3n profesional o t\u00e9cnica, programas virtuales, recuperaci\u00f3n de cr\u00e9ditos, GED y otras opciones de colocaci\u00f3n<sup>.12<\/sup> <\/li>\n\n\n\n<li>Los alumnos que reciben educaci\u00f3n especial a trav\u00e9s de Programas Educativos Individualizados (IEP) deben aprender en el Entorno Menos Restrictivo (LRE), o con alumnos no discapacitados en la \u00abm\u00e1xima medida posible\u00bb.  <\/li>\n\n\n\n<li>Los alumnos con PEI deben tener m\u00faltiples opciones de colocaci\u00f3n basadas en sus necesidades individuales que van desde la separaci\u00f3n total de las clases de educaci\u00f3n general hasta la plena inclusi\u00f3n en el programa de educaci\u00f3n general.\n<ul class=\"wp-block-list\">\n<li>Los alumnos hospitalizados deben poder seguir recibiendo su IEP a trav\u00e9s de la ense\u00f1anza en casa.  <\/li>\n\n\n\n<li>La ense\u00f1anza a domicilio est\u00e1 disponible si los alumnos necesitan aprender en casa o en otro entorno que el equipo del IEP identifique.  <\/li>\n\n\n\n<li>Los alumnos tambi\u00e9n pueden recibir instrucci\u00f3n en casa durante breves periodos de tiempo cuando un m\u00e9dico titulado o un psic\u00f3logo cl\u00ednico certifique que el alumno no puede asistir temporalmente a la escuela en persona.  <\/li>\n\n\n\n<li>Los estudiantes tambi\u00e9n pueden asistir a una escuela privada a trav\u00e9s de una colocaci\u00f3n del equipo del IEP o un equipo de la Ley de Servicios Integrales sin costo alguno para el cuidador si el equipo del IEP determina que la divisi\u00f3n escolar no puede proporcionar una educaci\u00f3n p\u00fablica gratuita y apropiada (FAPE) basada en el IEP del estudiante. Cuando se coloca al alumno en un programa privado, la divisi\u00f3n escolar que lo coloc\u00f3 sigue siendo responsable de la aplicaci\u00f3n del PEI<sup>.13<\/sup><\/li>\n<\/ul>\n<\/li>\n\n\n\n<li>Students&nbsp;who are compulsory school age (ages 5 to 18)&nbsp;do not have to attend public school&nbsp;if&nbsp;they are home schooled. Home school instruction may be provided if the instructor (usually a parent or caregiver):\n<ul class=\"wp-block-list\">\n<li>Tiene el t\u00edtulo de bachillerato;  <\/li>\n\n\n\n<li>Es un profesor cualificado seg\u00fan los requisitos del Consejo de Educaci\u00f3n del Estado;  <\/li>\n\n\n\n<li>Ofrece un plan de estudios o un programa de educaci\u00f3n a distancia; o  <\/li>\n\n\n\n<li>Presenta pruebas de ser capaz de proporcionar una educaci\u00f3n adecuada seg\u00fan la ley estatal.  <\/li>\n<\/ul>\n<\/li>\n\n\n\n<li>El padre o cuidador debe notificar al superintendente de la divisi\u00f3n escolar en agosto sobre la instrucci\u00f3n en el hogar con una lista de las materias que el alumno estudiar\u00e1 y que el instructor cumple con uno de los requisitos anteriores.  <\/li>\n\n\n\n<li>The parent or caregiver must report progress&nbsp;the student made&nbsp;by the following August, which may include:\n<ul class=\"wp-block-list\">\n<li>Rendimiento en una prueba estandarizada de rendimiento;  <\/li>\n\n\n\n<li>Evaluaci\u00f3n o valoraci\u00f3n aprobada por el superintendente para mostrar el crecimiento y el progreso que incluya una carta de evaluaci\u00f3n de una persona certificada que tenga conocimiento del progreso del estudiante o un bolet\u00edn de calificaciones o expediente acad\u00e9mico de un programa de educaci\u00f3n en casa<sup>.14<\/sup><\/li>\n<\/ul>\n<\/li>\n<\/ul>\n\n\n\t<\/div>\n<\/div>\n\n        <\/div>\n      <\/div>\n  <\/div>\n<\/div>\n\n\n\n\n  <style type=\"text\/css\">\n    #block_3c158277ec38b26ab204ee583011b6c1 {\n      \n                                        padding-left: calc(8 * 16px);\n                          padding-right: calc(8 * 16px);\n                  }\n\n    @media screen and (min-width: 768px) and (max-width: 991px) {\n      #block_3c158277ec38b26ab204ee583011b6c1 {\n          \n                                                  padding-left: calc(8 * 12px);\n                                padding-right: calc(8 * 12px);\n                        }\n    }\n\n    @media screen and (min-width: 480px) and (max-width: 767px) {\n      #block_3c158277ec38b26ab204ee583011b6c1 {\n          \n                                                  padding-left: calc(8 * 8px);\n                                padding-right: calc(8 * 8px);\n                        }\n    }\n\n    @media screen and (max-width: 479px) {\n      #block_3c158277ec38b26ab204ee583011b6c1 {\n          \n                                                  padding-left: calc(8 * 4px);\n                                padding-right: calc(8 * 4px);\n                        }\n    }\n\n  <\/style>\n\n\n<div id=\"block_3c158277ec38b26ab204ee583011b6c1\" class=\"accordion-section-block\">\n  <div class=\"container-fluid\">\n              <div class=\"accordion-section-heading-wrapper has-charcoal-background-color has-background-color\">\n          <div class=\"row row-heading\">\n            <div class=\"col-sm-12\">\n              <h2>Edad en la que el ni\u00f1o puede hacer valer sus derechos sobre su educaci\u00f3n<\/h2>\n              <p><\/p>\n              <span class=\"toggler\"><\/span>\n            <\/div>\n          <\/div>\n        <\/div>\n      \n      <div class=\"accordion-section-cols-wrapper has-whisper-background-color has-background-color\">\n        <div class=\"row row-cols\">\n          \n\n\n\n\n<style type=\"text\/css\">\n\t.edit-post-visual-editor [data-block=\"a4a8bdacf66625b14905963bc08db5bc\"] {\n\t\twidth: calc((12 \/ 12) * 100%)!important;\n\t\tmin-width: calc((12 \/ 12) * 100%)!important;\n\t}\n<\/style>\n\n<div id=\"block_a4a8bdacf66625b14905963bc08db5bc\" class=\"col-lg-12 custom-column-block\">\n\t<div class=\"custom-column-wrapper  \">\n\t\t\n\n<ul class=\"has-charcoal-color has-text-color wp-block-list\">\n<li>Los expedientes acad\u00e9micos de un alumno est\u00e1n protegidos contra la divulgaci\u00f3n sin el consentimiento informado por escrito.  <\/li>\n\n\n\n<li>Los padres o cuidadores tienen derecho a revisar, solicitar cambios y compartir los expedientes de un alumno.  <\/li>\n\n\n\n<li>Cuando un alumno cumple 18 a\u00f1os, estos derechos se transfieren al estudiante<sup>.15<\/sup><\/li>\n<\/ul>\n\n\n\t<\/div>\n<\/div>\n\n        <\/div>\n      <\/div>\n  <\/div>\n<\/div>\n\n\n\n\n  <style type=\"text\/css\">\n    #block_70c96775d213b6d316ab93ad098fd310 {\n      \n                                        padding-left: calc(8 * 16px);\n                          padding-right: calc(8 * 16px);\n                  }\n\n    @media screen and (min-width: 768px) and (max-width: 991px) {\n      #block_70c96775d213b6d316ab93ad098fd310 {\n          \n                                                  padding-left: calc(8 * 12px);\n                                padding-right: calc(8 * 12px);\n                        }\n    }\n\n    @media screen and (min-width: 480px) and (max-width: 767px) {\n      #block_70c96775d213b6d316ab93ad098fd310 {\n          \n                                                  padding-left: calc(8 * 8px);\n                                padding-right: calc(8 * 8px);\n                        }\n    }\n\n    @media screen and (max-width: 479px) {\n      #block_70c96775d213b6d316ab93ad098fd310 {\n          \n                                                  padding-left: calc(8 * 4px);\n                                padding-right: calc(8 * 4px);\n                        }\n    }\n\n  <\/style>\n\n\n<div id=\"block_70c96775d213b6d316ab93ad098fd310\" class=\"accordion-section-block\">\n  <div class=\"container-fluid\">\n              <div class=\"accordion-section-heading-wrapper has-charcoal-background-color has-background-color\">\n          <div class=\"row row-heading\">\n            <div class=\"col-sm-12\">\n              <h2>Notas a pie de p\u00e1gina<\/h2>\n              <p><\/p>\n              <span class=\"toggler\"><\/span>\n            <\/div>\n          <\/div>\n        <\/div>\n      \n      <div class=\"accordion-section-cols-wrapper has-whisper-background-color has-background-color\">\n        <div class=\"row row-cols\">\n          \n\n\n\n\n<style type=\"text\/css\">\n\t.edit-post-visual-editor [data-block=\"a4a8bdacf66625b14905963bc08db5bc\"] {\n\t\twidth: calc((12 \/ 12) * 100%)!important;\n\t\tmin-width: calc((12 \/ 12) * 100%)!important;\n\t}\n<\/style>\n\n<div id=\"block_a4a8bdacf66625b14905963bc08db5bc\" class=\"col-lg-12 custom-column-block\">\n\t<div class=\"custom-column-wrapper  \">\n\t\t\n\n<p class=\"has-charcoal-color has-text-color wp-block-paragraph\">1: C\u00d3DIGO DE VA. ANN. \u00a7 22.1-254(A).<\/p>\n\n\n\n<p class=\"has-charcoal-color has-text-color wp-block-paragraph\">2: VA. C\u00d3DIGO ANN. \u00a7 22.1-1.  <\/p>\n\n\n\n<p class=\"has-charcoal-color has-text-color wp-block-paragraph\">3: 8 VAC 20-81-30(B)<\/p>\n\n\n\n<p class=\"has-charcoal-color has-text-color wp-block-paragraph\">4: C\u00d3DIGO DE VA.ANN \u00a7 22.1-5(7)(D)<\/p>\n\n\n\n<p class=\"has-charcoal-color has-text-color wp-block-paragraph\">5: C\u00d3DIGO DE VA. ANN. \u00a7 22.1-3(A).<\/p>\n\n\n\n<p class=\"has-charcoal-color has-text-color wp-block-paragraph\">6: C\u00d3DIGO DE VA. ANN. \u00a7\u00a7 22.1-3.1; 22.1-270; 22.1-271.2.  <\/p>\n\n\n\n<p class=\"has-charcoal-color has-text-color wp-block-paragraph\">7: 1987-88Va. Op. Atty. Gen.374(1987).<\/p>\n\n\n\n<p class=\"has-charcoal-color has-text-color wp-block-paragraph\">8: C\u00d3DIGO DE VA. ANN. \u00a7 22-1-255.  <\/p>\n\n\n\n<p class=\"has-charcoal-color has-text-color wp-block-paragraph\">9: VA.CONST. arte. VIII, \u00a7 1; v\u00e9ase tambi\u00e9nPlyler v. Doe, 457 U.S. 202 (1982).<\/p>\n\n\n\n<p class=\"has-charcoal-color has-text-color wp-block-paragraph\">10: 8VAC20-81-150<\/p>\n\n\n\n<p class=\"has-charcoal-color has-text-color wp-block-paragraph\">11: Va. C\u00f3digo \u00a7 22.1-254  <\/p>\n\n\n\n<p class=\"has-charcoal-color has-text-color wp-block-paragraph\">12: Va. C\u00f3digo \u00a7 00.1-269.1<\/p>\n\n\n\n<p class=\"has-charcoal-color has-text-color wp-block-paragraph\">13: 8VAC20-81-130  <\/p>\n\n\n\n<p class=\"has-charcoal-color has-text-color wp-block-paragraph\">14: 22 Va. \u00a7 22.1-254.1  <\/p>\n\n\n\n<p class=\"has-charcoal-color has-text-color wp-block-paragraph\">15: Ley de Privacidad y Derechos Educativos de la Familia (FERPA) (20 U.S.C. \u00a7 1232g)  <\/p>\n\n\n\t<\/div>\n<\/div>\n\n        <\/div>\n      <\/div>\n  <\/div>\n<\/div>\n\n\t<\/div>\n<\/div>\n\n\t<\/div>\n<\/div>\n\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\n\t<style type=\"text\/css\">\n\t\t.edit-post-visual-editor [data-block=\"1f9a6efba0d484f2894a92586384d13c\"] .block-editor-block-list__layout {\n\t\t\tjustify-content: center;\n\t\t}\n\n\t\t\t<\/style>\n<\/div>\n\n\n\t<\/div>\n<\/div>","protected":false},"excerpt":{"rendered":"","protected":false},"author":4,"featured_media":0,"parent":10497,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"lajc-tax-roles":[],"lajc-tax-issues":[83],"lajc-tax-locations":[],"class_list":["post-10499","page","type-page","status-publish","hentry","lajc-tax-issues-youth-family-schools-es"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Matr\u00edcula escolar: Derechos y deberes - Legal Aid Justice Center<\/title>\n<meta name=\"description\" content=\"Informaci\u00f3n legal sobre derechos y responsabilidades de los estudiantes de Virginia en materia de matriculaci\u00f3n escolar.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.justice4all.org\/es\/que-hacemos\/juventud-familia-y-escuelas\/matricula-escolar-derechos-y-deberes\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Matr\u00edcula escolar: Derechos y deberes - Legal Aid Justice Center\" \/>\n<meta property=\"og:description\" content=\"Informaci\u00f3n legal sobre derechos y responsabilidades de los estudiantes de Virginia en materia de matriculaci\u00f3n escolar.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.justice4all.org\/es\/que-hacemos\/juventud-familia-y-escuelas\/matricula-escolar-derechos-y-deberes\/\" \/>\n<meta property=\"og:site_name\" content=\"Legal Aid Justice Center\" \/>\n<meta property=\"article:modified_time\" content=\"2023-07-25T21:51:26+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"8 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.justice4all.org\\\/es\\\/que-hacemos\\\/juventud-familia-y-escuelas\\\/matricula-escolar-derechos-y-deberes\\\/\",\"url\":\"https:\\\/\\\/www.justice4all.org\\\/es\\\/que-hacemos\\\/juventud-familia-y-escuelas\\\/matricula-escolar-derechos-y-deberes\\\/\",\"name\":\"Matr\u00edcula escolar: Derechos y deberes - Legal Aid Justice Center\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.justice4all.org\\\/es\\\/#website\"},\"datePublished\":\"2022-07-21T15:00:30+00:00\",\"dateModified\":\"2023-07-25T21:51:26+00:00\",\"description\":\"Informaci\u00f3n legal sobre derechos y responsabilidades de los estudiantes de Virginia en materia de matriculaci\u00f3n escolar.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.justice4all.org\\\/es\\\/que-hacemos\\\/juventud-familia-y-escuelas\\\/matricula-escolar-derechos-y-deberes\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.justice4all.org\\\/es\\\/que-hacemos\\\/juventud-familia-y-escuelas\\\/matricula-escolar-derechos-y-deberes\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.justice4all.org\\\/es\\\/que-hacemos\\\/juventud-familia-y-escuelas\\\/matricula-escolar-derechos-y-deberes\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.justice4all.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Qu\u00e9 hacemos\",\"item\":\"https:\\\/\\\/www.justice4all.org\\\/es\\\/que-hacemos\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Juventud, familia y escuelas\",\"item\":\"https:\\\/\\\/www.justice4all.org\\\/es\\\/que-hacemos\\\/juventud-familia-y-escuelas\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Matr\u00edcula escolar: Derechos y deberes\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.justice4all.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.justice4all.org\\\/es\\\/\",\"name\":\"Legal Aid Justice Center\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.justice4all.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Matr\u00edcula escolar: Derechos y deberes - Legal Aid Justice Center","description":"Informaci\u00f3n legal sobre derechos y responsabilidades de los estudiantes de Virginia en materia de matriculaci\u00f3n escolar.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.justice4all.org\/es\/que-hacemos\/juventud-familia-y-escuelas\/matricula-escolar-derechos-y-deberes\/","og_locale":"es_ES","og_type":"article","og_title":"Matr\u00edcula escolar: Derechos y deberes - Legal Aid Justice Center","og_description":"Informaci\u00f3n legal sobre derechos y responsabilidades de los estudiantes de Virginia en materia de matriculaci\u00f3n escolar.","og_url":"https:\/\/www.justice4all.org\/es\/que-hacemos\/juventud-familia-y-escuelas\/matricula-escolar-derechos-y-deberes\/","og_site_name":"Legal Aid Justice Center","article_modified_time":"2023-07-25T21:51:26+00:00","twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"8 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.justice4all.org\/es\/que-hacemos\/juventud-familia-y-escuelas\/matricula-escolar-derechos-y-deberes\/","url":"https:\/\/www.justice4all.org\/es\/que-hacemos\/juventud-familia-y-escuelas\/matricula-escolar-derechos-y-deberes\/","name":"Matr\u00edcula escolar: Derechos y deberes - Legal Aid Justice Center","isPartOf":{"@id":"https:\/\/www.justice4all.org\/es\/#website"},"datePublished":"2022-07-21T15:00:30+00:00","dateModified":"2023-07-25T21:51:26+00:00","description":"Informaci\u00f3n legal sobre derechos y responsabilidades de los estudiantes de Virginia en materia de matriculaci\u00f3n escolar.","breadcrumb":{"@id":"https:\/\/www.justice4all.org\/es\/que-hacemos\/juventud-familia-y-escuelas\/matricula-escolar-derechos-y-deberes\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.justice4all.org\/es\/que-hacemos\/juventud-familia-y-escuelas\/matricula-escolar-derechos-y-deberes\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.justice4all.org\/es\/que-hacemos\/juventud-familia-y-escuelas\/matricula-escolar-derechos-y-deberes\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.justice4all.org\/es\/"},{"@type":"ListItem","position":2,"name":"Qu\u00e9 hacemos","item":"https:\/\/www.justice4all.org\/es\/que-hacemos\/"},{"@type":"ListItem","position":3,"name":"Juventud, familia y escuelas","item":"https:\/\/www.justice4all.org\/es\/que-hacemos\/juventud-familia-y-escuelas\/"},{"@type":"ListItem","position":4,"name":"Matr\u00edcula escolar: Derechos y deberes"}]},{"@type":"WebSite","@id":"https:\/\/www.justice4all.org\/es\/#website","url":"https:\/\/www.justice4all.org\/es\/","name":"Legal Aid Justice Center","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.justice4all.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"}]}},"_links":{"self":[{"href":"https:\/\/www.justice4all.org\/es\/wp-json\/wp\/v2\/pages\/10499","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.justice4all.org\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.justice4all.org\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.justice4all.org\/es\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.justice4all.org\/es\/wp-json\/wp\/v2\/comments?post=10499"}],"version-history":[{"count":0,"href":"https:\/\/www.justice4all.org\/es\/wp-json\/wp\/v2\/pages\/10499\/revisions"}],"up":[{"embeddable":true,"href":"https:\/\/www.justice4all.org\/es\/wp-json\/wp\/v2\/pages\/10497"}],"wp:attachment":[{"href":"https:\/\/www.justice4all.org\/es\/wp-json\/wp\/v2\/media?parent=10499"}],"wp:term":[{"taxonomy":"lajc-tax-roles","embeddable":true,"href":"https:\/\/www.justice4all.org\/es\/wp-json\/wp\/v2\/lajc-tax-roles?post=10499"},{"taxonomy":"lajc-tax-issues","embeddable":true,"href":"https:\/\/www.justice4all.org\/es\/wp-json\/wp\/v2\/lajc-tax-issues?post=10499"},{"taxonomy":"lajc-tax-locations","embeddable":true,"href":"https:\/\/www.justice4all.org\/es\/wp-json\/wp\/v2\/lajc-tax-locations?post=10499"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}