{"id":17305,"date":"2023-09-12T15:33:58","date_gmt":"2023-09-12T15:33:58","guid":{"rendered":"https:\/\/www.justice4all.org\/?post_type=lajc_news&#038;p=17305"},"modified":"2026-02-05T03:00:48","modified_gmt":"2026-02-05T03:00:48","slug":"para-las-comunidades-con-las-comunidades","status":"publish","type":"lajc_news","link":"https:\/\/www.justice4all.org\/es\/news\/para-las-comunidades-con-las-comunidades\/","title":{"rendered":"M\u00e1s Justicia\/Menos Pobreza: Para las comunidades, con las comunidades"},"content":{"rendered":"\n\n\n\n\n<div id=\"block_6cad79f0262c5eb3b7f1a4b49be77c9d\" class=\"content-wrapper-block  style-normal bg-width-full \">\n\t<div class=\"container-fluid\">\n\t\t<div class=\"row justify-content-center\">\n\t\t\t<div class=\"col-lg-12\">\n\t\t\t\t\t\t\t\t\t<div class=\"row row-content justify-content-center\">\n\t\t\t\t\t\t\n\n\n\n  <style type=\"text\/css\">\n    #block_25ea5ce8a2638777112e28e1bf278d85 > div{\n                                        margin-left: calc(4 * 16px);\n                          margin-right: calc(4 * 16px);\n              \n                                        padding-left: calc(4 * 16px);\n                          padding-right: calc(4 * 16px);\n                  }\n\n    @media screen and (min-width: 768px) and (max-width: 991px) {\n      #block_25ea5ce8a2638777112e28e1bf278d85 > div{\n                                                  margin-left: calc(4 * 12px);  \n                                margin-right: calc(4 * 12px);  \n                    \n                                                  padding-left: calc(4 * 12px);\n                                padding-right: calc(4 * 12px);\n                        }\n    }\n\n    @media screen and (min-width: 480px) and (max-width: 767px) {\n      #block_25ea5ce8a2638777112e28e1bf278d85 > div{\n                                                  margin-left: calc(4 * 8px);  \n                                margin-right: calc(4 * 8px);  \n                    \n                                                  padding-left: calc(4 * 8px);\n                                padding-right: calc(4 * 8px);\n                        }\n    }\n\n    @media screen and (max-width: 479px) {\n      #block_25ea5ce8a2638777112e28e1bf278d85 > div{\n                                                  margin-left: calc(4 * 4px);  \n                                margin-right: calc(4 * 4px);  \n                    \n                                                  padding-left: calc(4 * 4px);\n                                padding-right: calc(4 * 4px);\n                        }\n    }\n\n  <\/style>\n\n<style type=\"text\/css\">\n\t.edit-post-visual-editor [data-block=\"25ea5ce8a2638777112e28e1bf278d85\"] {\n\t\twidth: calc((12 \/ 12) * 100%)!important;\n\t\tmin-width: calc((12 \/ 12) * 100%)!important;\n\t}\n<\/style>\n\n<div id=\"block_25ea5ce8a2638777112e28e1bf278d85\" class=\"col-lg-12 custom-column-block\">\n\t<div class=\"custom-column-wrapper  \">\n\t\t\n\n<figure class=\"wp-block-image size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.justice4all.org\/wp-content\/uploads\/2023\/09\/MicrosoftTeams-image-scaled.jpg\" alt=\"\" class=\"wp-image-17306\" width=\"1085\" height=\"460\" srcset=\"https:\/\/www.justice4all.org\/wp-content\/uploads\/2023\/09\/MicrosoftTeams-image-scaled.jpg 2560w, https:\/\/www.justice4all.org\/wp-content\/uploads\/2023\/09\/MicrosoftTeams-image-300x127.jpg 300w, https:\/\/www.justice4all.org\/wp-content\/uploads\/2023\/09\/MicrosoftTeams-image-1024x434.jpg 1024w, https:\/\/www.justice4all.org\/wp-content\/uploads\/2023\/09\/MicrosoftTeams-image-768x326.jpg 768w, https:\/\/www.justice4all.org\/wp-content\/uploads\/2023\/09\/MicrosoftTeams-image-1536x651.jpg 1536w, https:\/\/www.justice4all.org\/wp-content\/uploads\/2023\/09\/MicrosoftTeams-image-2048x868.jpg 2048w\" sizes=\"auto, (max-width: 1085px) 100vw, 1085px\" \/><\/figure>\n\n\n\t<\/div>\n<\/div>\n\n\n\n\n  <style type=\"text\/css\">\n    #block_b5b2f5569ca6bd78aa7f584440cc2ace > div{\n                                        margin-left: calc(4 * 16px);\n                          margin-right: calc(4 * 16px);\n              \n                                        padding-left: calc(4 * 16px);\n                          padding-right: calc(4 * 16px);\n                  }\n\n    @media screen and (min-width: 768px) and (max-width: 991px) {\n      #block_b5b2f5569ca6bd78aa7f584440cc2ace > div{\n                                                  margin-left: calc(4 * 12px);  \n                                margin-right: calc(4 * 12px);  \n                    \n                                                  padding-left: calc(4 * 12px);\n                                padding-right: calc(4 * 12px);\n                        }\n    }\n\n    @media screen and (min-width: 480px) and (max-width: 767px) {\n      #block_b5b2f5569ca6bd78aa7f584440cc2ace > div{\n                                                  margin-left: calc(4 * 8px);  \n                                margin-right: calc(4 * 8px);  \n                    \n                                                  padding-left: calc(4 * 8px);\n                                padding-right: calc(4 * 8px);\n                        }\n    }\n\n    @media screen and (max-width: 479px) {\n      #block_b5b2f5569ca6bd78aa7f584440cc2ace > div{\n                                                  margin-left: calc(4 * 4px);  \n                                margin-right: calc(4 * 4px);  \n                    \n                                                  padding-left: calc(4 * 4px);\n                                padding-right: calc(4 * 4px);\n                        }\n    }\n\n  <\/style>\n\n<style type=\"text\/css\">\n\t.edit-post-visual-editor [data-block=\"b5b2f5569ca6bd78aa7f584440cc2ace\"] {\n\t\twidth: calc((10 \/ 12) * 100%)!important;\n\t\tmin-width: calc((10 \/ 12) * 100%)!important;\n\t}\n<\/style>\n\n<div id=\"block_b5b2f5569ca6bd78aa7f584440cc2ace\" class=\"col-lg-10 custom-column-block\">\n\t<div class=\"custom-column-wrapper  \">\n\t\t\n\n<p class=\"wp-block-paragraph\">Cuando Jean Cahn, una abogada negra de Baltimore, se propuso crear un programa nacional de servicios jur\u00eddicos en 1964, quer\u00eda erigir instituciones que apoyaran a las personas con bajos ingresos y a las comunidades de color a ejercer su propio poder contra los sistemas que crean y perpet\u00faan la pobreza. Ella y su marido, Edgar Cahn, tuvieron la visi\u00f3n de que las organizaciones de servicios jur\u00eddicos se convertir\u00edan en \u00ababogados corporativos\u00bb para particulares y grupos comunitarios.  <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Durante d\u00e9cadas, el Centro de Justicia de Asistencia Jur\u00eddica se ha esforzado por llevar a cabo la visi\u00f3n original de Jean Cahn, una visi\u00f3n que a\u00fana la defensa tenaz de las personas con la defensa audaz de la reforma sist\u00e9mica. En nuestro plan estrat\u00e9gico m\u00e1s reciente, preguntamos a nuestros clientes y socios comunitarios: <strong>\u00ab\u00bfQu\u00e9 significa adoptar las ra\u00edces radicales de los servicios jur\u00eddicos en el siglo XXI?\u00bb.<\/strong> He aqu\u00ed parte de lo que aprendimos:  <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Empieza con una simple verdad. Si nuestro objetivo es acabar con el statu quo y dar poder a las personas que se encuentran en la base de la estructura de poder existente, no podemos adoptar un enfoque descendente. Un enfoque de arriba abajo no har\u00e1 sino reproducir las estructuras de poder que intentamos desmantelar.  <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tampoco veremos un cambio real y duradero. Un cambio real y duradero no se consigue con soluciones t\u00e9cnicas. Viene con el cambio cultural. La cultura es lo que impulsa el derecho y la pol\u00edtica, y el cambio cultural no puede ser prescrito por subvenciones o pol\u00edticos, o incluso&#8230; siento dec\u00edrselo&#8230; abogados de asistencia jur\u00eddica que act\u00faan solos.  <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La defensa impulsada por la comunidad tambi\u00e9n requiere un enfoque sist\u00e9mico. Como ha observado el <a href=\"https:\/\/r20.rs6.net\/tn.jsp?f=001eWu_RmXAFS6WX4PDO68Vu_KwY8HlPay6BTsonTO535R6WTx7QdMwnpyE9kGzhHtbQ2p153VR7TrLZO8YdSqMSOAyayORQpqXhimVOOZlis2YMhmAomvGn58RaSEQPTczmaKNb-7quaFFRSNA4g_ixD4zlLPdrVB4gHEqJXEIaWpi1gRw5MlJoT7UMHds6QBu&amp;c=fXcbUzez9V_SlCI9_tqVJ5bMZORYFJdr5MEhHTnoGc2heYQavh8uZw==&amp;ch=IMLXadMXt3kiGEdvNYNrM3FSrVnfYfQBQhvpLNAMSl_eTcKON4QYHQ==\" target=\"_blank\" rel=\"noreferrer noopener\">Racial Equity Institute<\/a>, \u00absi ves 100 peces panza arriba en el agua de un lago, no te preguntas: \u00ab\u00bfQu\u00e9 le pasa al pez?\u00bb. T\u00fa preguntas: \u00ab\u00bfQu\u00e9 le pasa al lago?\u00bb.  <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por eso, cuando vemos que cientos de miles de personas son desahuciadas, encarceladas, deportadas, pierden su seguro m\u00e9dico, son suspendidas en la escuela y mucho m\u00e1s, los defensores del LAJC no preguntan: \u00ab\u00bfQu\u00e9 les pasa a esas personas?\u00bb.  <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En el Centro de Justicia de Asistencia Jur\u00eddica nos preguntamos: \u00ab\u00bfQu\u00e9 falla en las estructuras jur\u00eddicas, pol\u00edticas y otras estructuras de poder que producen esos resultados?\u00bb. O, en otras palabras: \u00ab\u00bfQu\u00e9 le pasa al lago?\u00bb.<\/p>\n\n\n\n<div style=\"height:26px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-buttons is-content-justification-center is-layout-flex wp-container-core-buttons-is-layout-fe48e5de wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button is-style-primary\"><a class=\"wp-block-button__link wp-element-button\" href=\"https:\/\/www.justice4all.org\/es\/lajc-plan-estrategico-2022-2026\/\" target=\"_blank\" rel=\"noreferrer noopener\">PLAN ESTRAT\u00c9GICO DE LAJC<\/a><\/div>\n<\/div>\n\n\n\t<\/div>\n<\/div>\n\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\n\t<style type=\"text\/css\">\n\t\t.edit-post-visual-editor [data-block=\"6cad79f0262c5eb3b7f1a4b49be77c9d\"] .block-editor-block-list__layout {\n\t\t\tjustify-content: center;\n\t\t}\n\n\t\t\t<\/style>\n<\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":4,"featured_media":0,"parent":0,"menu_order":0,"template":"","format":"standard","meta":{"footnotes":""},"lajc-tax-news-type":[],"lajc-tax-roles":[],"lajc-tax-issues":[],"lajc-tax-locations":[],"class_list":["post-17305","lajc_news","type-lajc_news","status-publish","format-standard","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>M\u00e1s Justicia\/Menos Pobreza: Para las comunidades, con las comunidades - Legal Aid Justice Center<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.justice4all.org\/es\/news\/para-las-comunidades-con-las-comunidades\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"M\u00e1s Justicia\/Menos Pobreza: Para las comunidades, con las comunidades - Legal Aid Justice Center\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.justice4all.org\/es\/news\/para-las-comunidades-con-las-comunidades\/\" \/>\n<meta property=\"og:site_name\" content=\"Legal Aid Justice Center\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-05T03:00:48+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.justice4all.org\/wp-content\/uploads\/2023\/09\/MicrosoftTeams-image-scaled.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.justice4all.org\\\/es\\\/news\\\/para-las-comunidades-con-las-comunidades\\\/\",\"url\":\"https:\\\/\\\/www.justice4all.org\\\/es\\\/news\\\/para-las-comunidades-con-las-comunidades\\\/\",\"name\":\"M\u00e1s Justicia\\\/Menos Pobreza: Para las comunidades, con las comunidades - Legal Aid Justice Center\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.justice4all.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.justice4all.org\\\/es\\\/news\\\/para-las-comunidades-con-las-comunidades\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.justice4all.org\\\/es\\\/news\\\/para-las-comunidades-con-las-comunidades\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.justice4all.org\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/MicrosoftTeams-image-scaled.jpg\",\"datePublished\":\"2023-09-12T15:33:58+00:00\",\"dateModified\":\"2026-02-05T03:00:48+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.justice4all.org\\\/es\\\/news\\\/para-las-comunidades-con-las-comunidades\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.justice4all.org\\\/es\\\/news\\\/para-las-comunidades-con-las-comunidades\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.justice4all.org\\\/es\\\/news\\\/para-las-comunidades-con-las-comunidades\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.justice4all.org\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/MicrosoftTeams-image-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/www.justice4all.org\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/MicrosoftTeams-image-scaled.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.justice4all.org\\\/es\\\/news\\\/para-las-comunidades-con-las-comunidades\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.justice4all.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"M\u00e1s Justicia\\\/Menos Pobreza: Para las comunidades, con las comunidades\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.justice4all.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.justice4all.org\\\/es\\\/\",\"name\":\"Legal Aid Justice Center\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.justice4all.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"M\u00e1s Justicia\/Menos Pobreza: Para las comunidades, con las comunidades - Legal Aid Justice Center","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.justice4all.org\/es\/news\/para-las-comunidades-con-las-comunidades\/","og_locale":"es_ES","og_type":"article","og_title":"M\u00e1s Justicia\/Menos Pobreza: Para las comunidades, con las comunidades - Legal Aid Justice Center","og_url":"https:\/\/www.justice4all.org\/es\/news\/para-las-comunidades-con-las-comunidades\/","og_site_name":"Legal Aid Justice Center","article_modified_time":"2026-02-05T03:00:48+00:00","og_image":[{"url":"https:\/\/www.justice4all.org\/wp-content\/uploads\/2023\/09\/MicrosoftTeams-image-scaled.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"3 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.justice4all.org\/es\/news\/para-las-comunidades-con-las-comunidades\/","url":"https:\/\/www.justice4all.org\/es\/news\/para-las-comunidades-con-las-comunidades\/","name":"M\u00e1s Justicia\/Menos Pobreza: Para las comunidades, con las comunidades - Legal Aid Justice Center","isPartOf":{"@id":"https:\/\/www.justice4all.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.justice4all.org\/es\/news\/para-las-comunidades-con-las-comunidades\/#primaryimage"},"image":{"@id":"https:\/\/www.justice4all.org\/es\/news\/para-las-comunidades-con-las-comunidades\/#primaryimage"},"thumbnailUrl":"https:\/\/www.justice4all.org\/wp-content\/uploads\/2023\/09\/MicrosoftTeams-image-scaled.jpg","datePublished":"2023-09-12T15:33:58+00:00","dateModified":"2026-02-05T03:00:48+00:00","breadcrumb":{"@id":"https:\/\/www.justice4all.org\/es\/news\/para-las-comunidades-con-las-comunidades\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.justice4all.org\/es\/news\/para-las-comunidades-con-las-comunidades\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.justice4all.org\/es\/news\/para-las-comunidades-con-las-comunidades\/#primaryimage","url":"https:\/\/www.justice4all.org\/wp-content\/uploads\/2023\/09\/MicrosoftTeams-image-scaled.jpg","contentUrl":"https:\/\/www.justice4all.org\/wp-content\/uploads\/2023\/09\/MicrosoftTeams-image-scaled.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.justice4all.org\/es\/news\/para-las-comunidades-con-las-comunidades\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.justice4all.org\/es\/"},{"@type":"ListItem","position":2,"name":"M\u00e1s Justicia\/Menos Pobreza: Para las comunidades, con las comunidades"}]},{"@type":"WebSite","@id":"https:\/\/www.justice4all.org\/es\/#website","url":"https:\/\/www.justice4all.org\/es\/","name":"Legal Aid Justice Center","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.justice4all.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"}]}},"_links":{"self":[{"href":"https:\/\/www.justice4all.org\/es\/wp-json\/wp\/v2\/lajc_news\/17305","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.justice4all.org\/es\/wp-json\/wp\/v2\/lajc_news"}],"about":[{"href":"https:\/\/www.justice4all.org\/es\/wp-json\/wp\/v2\/types\/lajc_news"}],"author":[{"embeddable":true,"href":"https:\/\/www.justice4all.org\/es\/wp-json\/wp\/v2\/users\/4"}],"version-history":[{"count":0,"href":"https:\/\/www.justice4all.org\/es\/wp-json\/wp\/v2\/lajc_news\/17305\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.justice4all.org\/es\/wp-json\/wp\/v2\/media?parent=17305"}],"wp:term":[{"taxonomy":"lajc-tax-news-type","embeddable":true,"href":"https:\/\/www.justice4all.org\/es\/wp-json\/wp\/v2\/lajc-tax-news-type?post=17305"},{"taxonomy":"lajc-tax-roles","embeddable":true,"href":"https:\/\/www.justice4all.org\/es\/wp-json\/wp\/v2\/lajc-tax-roles?post=17305"},{"taxonomy":"lajc-tax-issues","embeddable":true,"href":"https:\/\/www.justice4all.org\/es\/wp-json\/wp\/v2\/lajc-tax-issues?post=17305"},{"taxonomy":"lajc-tax-locations","embeddable":true,"href":"https:\/\/www.justice4all.org\/es\/wp-json\/wp\/v2\/lajc-tax-locations?post=17305"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}