{"id":13151,"date":"2022-09-21T12:10:46","date_gmt":"2022-09-21T12:10:46","guid":{"rendered":"https:\/\/lajc2023stg.wpengine.com\/news\/se-recurre-la-sentencia-sobre-discriminacion-en-un-parque-de-autocaravanas\/"},"modified":"2022-09-21T12:10:46","modified_gmt":"2022-09-21T12:10:46","slug":"se-recurre-la-sentencia-sobre-discriminacion-en-un-parque-de-autocaravanas","status":"publish","type":"lajc_news","link":"https:\/\/www.justice4all.org\/es\/news\/se-recurre-la-sentencia-sobre-discriminacion-en-un-parque-de-autocaravanas\/","title":{"rendered":"Se recurre la sentencia sobre discriminaci\u00f3n en un parque de autocaravanas"},"content":{"rendered":"<div class=\"lajc-m-content\">\n<h1>Apoyo del DOJ y de grupos de defensa de la inmigraci\u00f3n y la vivienda justa<\/h1>\n<p>Los demandantes en un largo caso de discriminaci\u00f3n en materia de vivienda pretenden anular una sentencia de un tribunal de distrito que permitir\u00eda al Waples Mobile Home Park de Fairfax (Virginia) desahuciar a los inquilinos por la condici\u00f3n de inmigrante de un familiar.  <a href=\"https:\/\/www.zuckerman.com\/sites\/default\/files\/2022-09\/2022-09-08%20Reyes%20v%20Waples%20-%20Appellants%27%20Opening%20Brief.pdf\">El recurso<\/a>dirigida por el  <a href=\"https:\/\/www.justice4all.org\/es\/\">Centro de Justicia y Asistencia Jur\u00eddica<\/a>  y el abogado pro bono Zuckerman Spaeder LLP, ha obtenido el apoyo del Departamento de Justicia (DOJ) y de numerosas organizaciones de vivienda justa y derechos civiles, que han presentado escritos amicus curiae afirmando que la sentencia del tribunal de distrito, de confirmarse, tendr\u00eda consecuencias dram\u00e1ticas tanto para los arrendadores como para los inmigrantes en todo el pa\u00eds.<\/p>\n<p>Presentada en 2016, la demanda alega que una pol\u00edtica de Waples que exige a los inquilinos adultos que demuestren su estatus migratorio legal afecta injustamente a los latinos y, por lo tanto, viola la Ley de Vivienda Justa (FHA). Cuando Waples comenz\u00f3 a aplicar la pol\u00edtica en 2015, oblig\u00f3 a los demandantes -todas las familias en las que el padre tiene estatus legal en Estados Unidos, la madre es indocumentada y los hijos son ciudadanos estadounidenses- y a otros a perder su vivienda.<\/p>\n<p>Waples ha argumentado que su pol\u00edtica es necesaria para evitar la responsabilidad penal en virtud de una ley federal que proh\u00edbe acoger a inmigrantes indocumentados. A pesar de que este argumento fue rechazado dos veces en los tribunales, incluso en 2018 por el Tribunal de Apelaciones del Cuarto Circuito, una sentencia del tribunal de distrito de mayo de 2022 fall\u00f3 a favor de Waples bas\u00e1ndose en su alegaci\u00f3n \u00abantiaburrimiento\u00bb. La apelaci\u00f3n de los demandantes, presentada el 8 de septiembre, ser\u00e1 vista de nuevo por el Cuarto Circuito.<\/p>\n<p>Seg\u00fan el <a href=\"https:\/\/www.justice.gov\/crt\/case-document\/brief-amicus-reyes-v-waples-mobile-home-park\">escrito de amicus curiae del DOJ<\/a>, presentado junto con el Departamento de Vivienda y Desarrollo Urbano, la sentencia del tribunal de distrito debe ser revocada porque \u00abno analiz\u00f3 adecuadamente si Waples corr\u00eda el riesgo de incurrir en responsabilidad penal por encubrimiento.\u00bb El DOJ, que es la autoridad encargada de hacer cumplir la ley federal contra el acoso, desmonta a continuaci\u00f3n el argumento de Waples de que su pol\u00edtica de control era necesaria para evitar esa responsabilidad, afirmando que \u00abno persigue a los arrendadores de viviendas por el mero hecho de que, en el curso normal de su actividad, no comprueben el estatus migratorio de todas las personas que viven en sus alquileres\u00bb.<\/p>\n<p><a href=\"https:\/\/www.justice4all.org\/who-we-are-2\/staff\/\">Sim\u00f3n Sandoval-Moshenberg<\/a>director jur\u00eddico del Programa de Defensa de los Inmigrantes del Centro de Justicia de Asistencia Jur\u00eddica, coment\u00f3: \u00abWaples argument\u00f3 ante el tribunal que lo prudente y cauteloso era comprobar la situaci\u00f3n de inmigraci\u00f3n de sus inquilinos. Pero la presentaci\u00f3n del DOJ deja claro que lo prudente y cauteloso es simplemente no hacer preguntas sobre el estatus migratorio. Los federales no le procesar\u00e1n si no pregunta, pero puede que le interpongan una demanda o una acci\u00f3n coercitiva en virtud de la Ley de Vivienda Justa si pregunta\u00bb.<\/p>\n<p>Waples fue incapaz de demostrar al Tribunal de Distrito que corr\u00edan el riesgo real de ser procesados por alquilar a inmigrantes indocumentados, o incluso que realmente consideraron el riesgo de ser procesados al decidir aplicar esta pol\u00edtica, que exist\u00eda en los libros desde hac\u00eda d\u00e9cadas, pero que en gran medida fue ignorada.<\/p>\n<p>Zuckerman Spaeder abogado  <a href=\"https:\/\/www.zuckerman.com\/people\/nicholas-m-dicarlo\">Nicholas DiCarlo<\/a>  dijo: \u00abLa defensa de Waples se ha centrado en la percepci\u00f3n de preocupaciones contra el acoso, pero de hecho, su repentina exigencia de pruebas de la condici\u00f3n de inmigrante de los inquilinos era totalmente ajena a tales preocupaciones. El argumento contra el acoso es una cortina de humo que ni explica las acciones de Waples ni proporciona una base legal razonable para apoyar su pol\u00edtica discriminatoria.\u00bb<\/p>\n<p>Adem\u00e1s de refutar las conclusiones jur\u00eddicas del tribunal de distrito, otros amici hacen hincapi\u00e9 en la importante repercusi\u00f3n nacional de la confirmaci\u00f3n de la sentencia.<\/p>\n<p>John Trasvi\u00f1a, que fue el principal asesor jur\u00eddico del Director del Servicio de Inmigraci\u00f3n y Control de Aduanas de Estados Unidos y secretario adjunto del Departamento de Vivienda y Desarrollo Urbano, <a href=\"https:\/\/www.zuckerman.com\/sites\/default\/files\/2022-09\/0028.%20%2809-15-2022%29%20AMICUS%20CURIAE%20BRIEF%20by%20John%20D.%20Trasvina%20Former%20HUD%20Assistant%20Secretary%20for%20Fair%20Housing%20and%20Equal%20O.pdf\">escribi\u00f3<\/a> lo siguienteSi el tribunal de distrito tuviera raz\u00f3n al afirmar que los arrendadores pueden incurrir en responsabilidad penal por el mero hecho de alquilar a un indocumentado&#8230; se producir\u00eda una conmoci\u00f3n en el sector de la vivienda\u00bb y se producir\u00eda un \u00abcambio radical no s\u00f3lo en la vida de los indocumentados&#8230;., sino tambi\u00e9n en la de millones de ciudadanos estadounidenses y residentes legales que pueden&#8230; parecer extranjeros a un posible arrendador\u00bb. El escrito se\u00f1alaba que, de los aproximadamente 11 millones de indocumentados que hay en Estados Unidos, unos 7 millones son inquilinos que se ver\u00edan directamente afectados por esta sentencia.<\/p>\n<p>Un grupo de siete organizaciones de derechos civiles y vivienda justa, entre ellas la National Fair Housing Alliance y la American Civil Liberties Union,  <a href=\"https:\/\/www.zuckerman.com\/sites\/default\/files\/2022-09\/2022-09-15%20%5BECF%20029%5D%20Amicus%20Brief_Nat%27l%20Fair%20Housing%20Alliance.pdf\">present\u00f3 un escrito<\/a> en el que afirmaba que la decisi\u00f3n del tribunal de distrito \u00abimpedir\u00eda y perturbar\u00eda a los proveedores de vivienda&#8230; el cumplimiento de su misi\u00f3n de ayudar a garantizar una vivienda segura, asequible y accesible para todas las personas y familias\u00bb. Otros firmantes del escrito son el Lawyers&#8217; Committee for Civil Rights Under Law, Equal Rights Center y Housing Opportunities Made Equal of Virginia.<\/p>\n<p><a href=\"https:\/\/www.zuckerman.com\/sites\/default\/files\/2022-09\/0026.%20%2809-15-2022%29%20AMICUS%20CURIAE%20BRIEF%20by%20Amicus%20Curiae%20National%20Housing%20Law%20Project%20National%20Low%20Income%20Housing%20Coali.pdf\">Otro breve<\/a>  fue presentada por el National Housing Law Project, el National Homelessness Law Center, el National Immigrant Law Center y la National Low Income Housing Coalition, que escribieron que \u00abpermitir que se mantenga una pol\u00edtica tan descaradamente discriminatoria dar\u00e1 luz verde no s\u00f3lo a que los propietarios se nieguen a alquilar a hogares en funci\u00f3n de su estatus migratorio real o percibido, sino que podr\u00eda invitar a una serie de otros comportamientos ilegales por parte de los propietarios\u00bb.<\/p>\n<p>Otras personas que trabajan en el caso son <a href=\"https:\/\/www.zuckerman.com\/people\/adam-abelson\">Adam Abelson<\/a>, de Zuckerman Spaeder, y del Centro de Justicia de Asistencia Jur\u00eddica, Nady Peralta, Clay Warner y Larisa Zehr.<\/p>\n<p>El caso es Reyes, et al. v. Waples Mobile Home Park Limited Partnership, et al., No. 22-1660.<\/p>\n<p>Fuente: <a href=\"https:\/\/www.zuckerman.com\/news\/press-release\/mobile-home-park-discrimination-ruling-appealed-doj-immigration-fair-housing-groups-provide-support\">https:\/\/www.zuckerman.com\/news\/press-release\/mobile-home-park-discrimination-ruling-appealed-doj-immigration-fair-housing-groups-provide-support<\/a><\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Apoyo del DOJ y de grupos de defensa de la inmigraci\u00f3n y la vivienda justa Los demandantes en un largo caso de discriminaci\u00f3n en materia de vivienda pretenden anular una sentencia de un tribunal de distrito que permitir\u00eda al Waples Mobile Home Park de Fairfax (Virginia) desahuciar a los inquilinos por la condici\u00f3n de inmigrante [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":0,"parent":0,"menu_order":0,"template":"","format":"standard","meta":{"footnotes":""},"lajc-tax-news-type":[],"lajc-tax-roles":[],"lajc-tax-issues":[86],"lajc-tax-locations":[],"class_list":["post-13151","lajc_news","type-lajc_news","status-publish","format-standard","hentry","lajc-tax-issues-vivienda"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Se recurre la sentencia sobre discriminaci\u00f3n en un parque de autocaravanas - Legal Aid Justice Center<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.justice4all.org\/es\/news\/se-recurre-la-sentencia-sobre-discriminacion-en-un-parque-de-autocaravanas\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Se recurre la sentencia sobre discriminaci\u00f3n en un parque de autocaravanas - Legal Aid Justice Center\" \/>\n<meta property=\"og:description\" content=\"Apoyo del DOJ y de grupos de defensa de la inmigraci\u00f3n y la vivienda justa Los demandantes en un largo caso de discriminaci\u00f3n en materia de vivienda pretenden anular una sentencia de un tribunal de distrito que permitir\u00eda al Waples Mobile Home Park de Fairfax (Virginia) desahuciar a los inquilinos por la condici\u00f3n de inmigrante [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.justice4all.org\/es\/news\/se-recurre-la-sentencia-sobre-discriminacion-en-un-parque-de-autocaravanas\/\" \/>\n<meta property=\"og:site_name\" content=\"Legal Aid Justice Center\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.justice4all.org\\\/es\\\/news\\\/se-recurre-la-sentencia-sobre-discriminacion-en-un-parque-de-autocaravanas\\\/\",\"url\":\"https:\\\/\\\/www.justice4all.org\\\/es\\\/news\\\/se-recurre-la-sentencia-sobre-discriminacion-en-un-parque-de-autocaravanas\\\/\",\"name\":\"Se recurre la sentencia sobre discriminaci\u00f3n en un parque de autocaravanas - Legal Aid Justice Center\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.justice4all.org\\\/es\\\/#website\"},\"datePublished\":\"2022-09-21T12:10:46+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.justice4all.org\\\/es\\\/news\\\/se-recurre-la-sentencia-sobre-discriminacion-en-un-parque-de-autocaravanas\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.justice4all.org\\\/es\\\/news\\\/se-recurre-la-sentencia-sobre-discriminacion-en-un-parque-de-autocaravanas\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.justice4all.org\\\/es\\\/news\\\/se-recurre-la-sentencia-sobre-discriminacion-en-un-parque-de-autocaravanas\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.justice4all.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Se recurre la sentencia sobre discriminaci\u00f3n en un parque de autocaravanas\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.justice4all.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.justice4all.org\\\/es\\\/\",\"name\":\"Legal Aid Justice Center\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.justice4all.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Se recurre la sentencia sobre discriminaci\u00f3n en un parque de autocaravanas - Legal Aid Justice Center","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.justice4all.org\/es\/news\/se-recurre-la-sentencia-sobre-discriminacion-en-un-parque-de-autocaravanas\/","og_locale":"es_ES","og_type":"article","og_title":"Se recurre la sentencia sobre discriminaci\u00f3n en un parque de autocaravanas - Legal Aid Justice Center","og_description":"Apoyo del DOJ y de grupos de defensa de la inmigraci\u00f3n y la vivienda justa Los demandantes en un largo caso de discriminaci\u00f3n en materia de vivienda pretenden anular una sentencia de un tribunal de distrito que permitir\u00eda al Waples Mobile Home Park de Fairfax (Virginia) desahuciar a los inquilinos por la condici\u00f3n de inmigrante [&hellip;]","og_url":"https:\/\/www.justice4all.org\/es\/news\/se-recurre-la-sentencia-sobre-discriminacion-en-un-parque-de-autocaravanas\/","og_site_name":"Legal Aid Justice Center","twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"5 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.justice4all.org\/es\/news\/se-recurre-la-sentencia-sobre-discriminacion-en-un-parque-de-autocaravanas\/","url":"https:\/\/www.justice4all.org\/es\/news\/se-recurre-la-sentencia-sobre-discriminacion-en-un-parque-de-autocaravanas\/","name":"Se recurre la sentencia sobre discriminaci\u00f3n en un parque de autocaravanas - Legal Aid Justice Center","isPartOf":{"@id":"https:\/\/www.justice4all.org\/es\/#website"},"datePublished":"2022-09-21T12:10:46+00:00","breadcrumb":{"@id":"https:\/\/www.justice4all.org\/es\/news\/se-recurre-la-sentencia-sobre-discriminacion-en-un-parque-de-autocaravanas\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.justice4all.org\/es\/news\/se-recurre-la-sentencia-sobre-discriminacion-en-un-parque-de-autocaravanas\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.justice4all.org\/es\/news\/se-recurre-la-sentencia-sobre-discriminacion-en-un-parque-de-autocaravanas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.justice4all.org\/es\/"},{"@type":"ListItem","position":2,"name":"Se recurre la sentencia sobre discriminaci\u00f3n en un parque de autocaravanas"}]},{"@type":"WebSite","@id":"https:\/\/www.justice4all.org\/es\/#website","url":"https:\/\/www.justice4all.org\/es\/","name":"Legal Aid Justice Center","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.justice4all.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"}]}},"_links":{"self":[{"href":"https:\/\/www.justice4all.org\/es\/wp-json\/wp\/v2\/lajc_news\/13151","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.justice4all.org\/es\/wp-json\/wp\/v2\/lajc_news"}],"about":[{"href":"https:\/\/www.justice4all.org\/es\/wp-json\/wp\/v2\/types\/lajc_news"}],"author":[{"embeddable":true,"href":"https:\/\/www.justice4all.org\/es\/wp-json\/wp\/v2\/users\/4"}],"version-history":[{"count":0,"href":"https:\/\/www.justice4all.org\/es\/wp-json\/wp\/v2\/lajc_news\/13151\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.justice4all.org\/es\/wp-json\/wp\/v2\/media?parent=13151"}],"wp:term":[{"taxonomy":"lajc-tax-news-type","embeddable":true,"href":"https:\/\/www.justice4all.org\/es\/wp-json\/wp\/v2\/lajc-tax-news-type?post=13151"},{"taxonomy":"lajc-tax-roles","embeddable":true,"href":"https:\/\/www.justice4all.org\/es\/wp-json\/wp\/v2\/lajc-tax-roles?post=13151"},{"taxonomy":"lajc-tax-issues","embeddable":true,"href":"https:\/\/www.justice4all.org\/es\/wp-json\/wp\/v2\/lajc-tax-issues?post=13151"},{"taxonomy":"lajc-tax-locations","embeddable":true,"href":"https:\/\/www.justice4all.org\/es\/wp-json\/wp\/v2\/lajc-tax-locations?post=13151"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}